{"id":25,"date":"2024-08-19T11:42:34","date_gmt":"2024-08-19T11:42:34","guid":{"rendered":"https:\/\/idg-lab.com.sa\/?page_id=25"},"modified":"2026-06-26T21:59:10","modified_gmt":"2026-06-26T21:59:10","slug":"home","status":"publish","type":"page","link":"https:\/\/idg-lab.com.sa\/ar\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"25\" class=\"elementor elementor-25\" data-elementor-post-type=\"page\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-1541322 e-con-full bg-moving-animation-sm e-flex e-con e-parent\" data-id=\"1541322\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-03dd5b7 e-flex e-con-boxed e-con e-child\" data-id=\"03dd5b7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-89a0083 e-con-full e-flex e-con e-child\" data-id=\"89a0083\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bdea47d elementor-headline--style-rotate elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-animated-headline\" data-id=\"bdea47d\" data-element_type=\"widget\" data-settings=\"{&quot;headline_style&quot;:&quot;rotate&quot;,&quot;animation_type&quot;:&quot;blinds&quot;,&quot;rotating_text&quot;:&quot;Royal Edition\\nHigh Diamond&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;rotate_iteration_delay&quot;:2500}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-headline elementor-headline-animation-type-blinds elementor-headline-letters\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Variety<\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">\n\t\t\t\tRoyal&nbsp;Edition\t\t\t<\/span>\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text\">\n\t\t\t\tHigh&nbsp;Diamond\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\"><br>Just For A Queens<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04ecc0f elementor-headline--style-rotate elementor-widget elementor-widget-animated-headline\" data-id=\"04ecc0f\" data-element_type=\"widget\" data-settings=\"{&quot;headline_style&quot;:&quot;rotate&quot;,&quot;animation_type&quot;:&quot;drop-in&quot;,&quot;rotating_text&quot;:&quot;\\u0646\\u062e\\u062a\\u0628\\u0631 \\u062c\\u0648\\u0627\\u0647\\u0631\\u0643\\n\\u0646\\u062e\\u062a\\u0628\\u0631 \\u062c\\u0648\\u0627\\u0647\\u0631\\u0643&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;rotate_iteration_delay&quot;:2500}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-headline elementor-headline-animation-type-drop-in\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">\u062f\u0639\u0648\u0646\u0627<\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">\n\t\t\t\t\u0646\u062e\u062a\u0628\u0631&nbsp;\u062c\u0648\u0627\u0647\u0631\u0643\t\t\t<\/span>\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text\">\n\t\t\t\t\u0646\u062e\u062a\u0628\u0631&nbsp;\u062c\u0648\u0627\u0647\u0631\u0643\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\"><br>\u0644\u0644\u062a\u0623\u0643\u062f \u0645\u0646 \u0635\u062d\u062a\u0647\u0627!<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02d36e5 elementor-widget elementor-widget-text-editor\" data-id=\"02d36e5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>IDG \u0647\u0648 \u0645\u062e\u062a\u0628\u0631 \u0631\u0627\u0626\u062f \u0645\u062a\u062e\u0635\u0635 \u0641\u064a \u0641\u062d\u0635 \u0648\u062a\u0642\u064a\u064a\u0645 \u0627\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629 \u0648\u0627\u0644\u0623\u0644\u0645\u0627\u0633.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be87553 btn-cms my-btn elementor-widget elementor-widget-eael-creative-button\" data-id=\"be87553\" data-element_type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--wayra\" href=\"https:\/\/idg-lab.com.sa\/contact-us\/\" data-text=\"Go!\">\n\n\t    \n                <div class=\"creative-button-inner\">\n\n                    \n                    <span class=\"cretive-button-text\">\u0627\u062a\u0635\u0644 \u0628\u0646\u0627<\/span>\n\n                                            <span class=\"eael-creative-button-icon-right\"><i aria-hidden=\"true\" class=\"hm hm-arrow-right\"><\/i><\/span>                                    <\/div>\n\t                        <\/a>\n        <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-e12bd27 e-con-full e-flex e-con e-child\" data-id=\"e12bd27\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-ccefda9 e-con-full e-flex e-con e-child\" data-id=\"ccefda9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-50e28ff e-flex e-con-boxed e-con e-child\" data-id=\"50e28ff\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-fc55223 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"fc55223\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e79b5c elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9e79b5c\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-x-twitter\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u062a\u0648\u064a\u062a\u0631<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0627\u0646\u0633\u062a\u062c\u0631\u0627\u0645<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin-in\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0644\u064a\u0646\u0643\u062f\u0625\u0646<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-tiktok\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u062a\u064a\u0643 \u062a\u0648\u0643<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-7ffeb24 e-con-full e-flex e-con e-child\" data-id=\"7ffeb24\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb1908e elementor-widget-mobile__width-initial elementor-absolute elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"fb1908e\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.4,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"715\" height=\"1024\" src=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/2024\/08\/L5EW34K-3-715x1024-1.png\" class=\"attachment-full size-full wp-image-758\" alt=\"\" srcset=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/2024\/08\/L5EW34K-3-715x1024-1.png 715w, https:\/\/idg-lab.com.sa\/wp-content\/uploads\/2024\/08\/L5EW34K-3-715x1024-1-209x300.png 209w\" sizes=\"(max-width: 715px) 100vw, 715px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-7469bf0 e-con-full e-flex e-con e-child\" data-id=\"7469bf0\" data-element_type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-2616933 e-con-full m0p0 e-flex e-con e-child\" data-id=\"2616933\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7179c42 elementor-widget elementor-widget-heading\" data-id=\"7179c42\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0639\u0646\u0648\u0627\u0646\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b22c5e elementor-widget elementor-widget-text-editor\" data-id=\"3b22c5e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0645\u0631\u0643\u0632 \u0627\u0644\u0623\u0646\u062f\u0644\u0633 \u0627\u0644\u062a\u062c\u0627\u0631\u064a <br \/>\u0628\u0648\u0627\u0628\u0629 \u0666 \u0627\u0644\u062f\u0648\u0631\u00a0\u0627\u0644\u0627\u0648\u0644<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-90f7075 e-con-full m0p0 e-flex e-con e-child\" data-id=\"90f7075\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-105fe53 elementor-widget elementor-widget-heading\" data-id=\"105fe53\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u062a\u0648\u0627\u0635\u0644 \u0645\u0639\u0646\u0627<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d607dfe cd elementor-widget elementor-widget-text-editor\" data-id=\"d607dfe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>E : info@idg-lab.com.sa<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-83cbde6 e-flex e-con-boxed e-con e-parent\" data-id=\"83cbde6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-4a2d5a0 e-con-full e-flex e-con e-child\" data-id=\"4a2d5a0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44be4d1 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"44be4d1\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"853pt\" height=\"813pt\" viewBox=\"0 0 853 813\"><g id=\"#ffffffff\"><\/g><g id=\"#025331ff\"><path fill=\"#025331\" opacity=\"1.00\" d=\" M 393.46 16.69 C 458.45 11.91 524.67 23.08 584.09 50.01 C 654.98 81.85 715.76 135.47 756.63 201.53 C 792.37 258.97 812.53 325.96 814.60 393.56 C 814.61 400.38 815.64 407.19 814.79 414.00 C 813.87 481.47 795.10 548.65 760.54 606.64 C 728.27 661.04 682.66 707.45 628.90 740.77 C 575.73 773.78 514.45 793.54 452.04 797.92 C 444.71 798.63 437.32 798.31 430.00 799.10 C 420.65 799.82 411.34 798.46 402.00 798.38 C 327.51 794.77 254.25 769.00 193.92 725.13 C 132.28 680.53 83.58 617.96 56.67 546.70 C 42.97 510.60 34.59 472.44 32.19 433.90 C 31.15 426.65 31.65 419.30 31.44 412.00 C 30.42 359.10 40.69 306.04 60.94 257.16 C 89.99 186.93 140.22 125.78 203.02 83.07 C 259.17 44.63 325.66 21.70 393.46 16.69 M 398.41 30.47 C 312.37 35.61 228.72 72.00 165.88 130.94 C 123.92 169.76 91.03 218.31 70.43 271.62 C 53.08 316.56 44.38 364.85 45.37 413.00 C 45.59 419.62 45.08 426.31 46.17 432.88 C 48.31 468.06 55.80 502.91 67.84 536.03 C 93.01 605.64 139.36 667.29 198.93 711.16 C 262.08 757.99 340.29 784.70 419.00 784.75 C 475.74 785.90 532.58 773.28 583.86 749.07 C 643.24 721.11 695.02 677.33 732.65 623.58 C 776.69 560.97 801.22 484.62 800.72 408.00 C 801.28 352.24 788.59 296.49 764.73 246.14 C 730.96 174.61 674.13 114.27 604.77 76.24 C 542.26 41.67 469.67 25.52 398.41 30.47 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 527.44 57.48 C 535.25 54.30 544.77 59.86 546.56 67.92 C 546.91 70.50 546.67 73.10 546.54 75.69 C 537.23 73.39 528.31 69.78 519.10 67.15 C 518.93 62.34 523.45 59.14 527.44 57.48 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 392.23 76.50 C 391.84 70.21 396.46 64.50 402.22 62.52 C 406.41 62.16 411.19 61.52 414.78 64.24 C 419.03 66.78 421.15 71.67 421.70 76.42 C 411.87 76.66 402.05 76.53 392.23 76.50 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 424.44 76.39 C 424.84 70.10 428.99 64.10 435.21 62.46 C 439.37 62.17 444.14 61.54 447.62 64.40 C 451.72 67.03 453.82 71.71 454.29 76.43 C 444.34 76.58 434.38 76.66 424.44 76.39 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 496.11 83.35 C 498.16 73.89 510.83 70.32 518.27 75.80 C 523.69 79.33 525.17 86.34 524.19 92.37 C 514.80 89.46 505.49 86.29 496.11 83.35 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 527.06 93.36 C 529.08 85.08 539.20 81.13 546.71 84.42 C 552.98 86.95 556.57 94.36 555.33 100.89 C 554.60 102.32 552.84 101.53 551.68 101.32 C 543.42 98.83 535.27 96.00 527.06 93.36 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 385.88 85.10 C 390.90 83.82 396.79 84.58 400.52 88.46 C 403.69 91.13 404.95 95.29 405.00 99.31 C 395.65 99.45 386.30 99.51 376.96 99.32 C 376.61 98.98 375.90 98.31 375.55 97.98 C 376.32 92.23 380.30 86.92 385.88 85.10 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 450.34 85.40 C 456.15 83.34 463.25 84.82 467.08 89.86 C 469.30 92.48 470.39 95.92 470.51 99.33 C 460.80 99.50 451.08 99.39 441.36 99.39 C 440.65 93.37 444.78 87.48 450.34 85.40 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 473.85 99.75 C 475.48 90.30 488.40 86.60 495.69 92.19 C 501.15 95.72 502.64 102.62 501.46 108.69 C 492.22 105.83 483.01 102.87 473.85 99.75 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 319.20 102.34 C 326.75 96.53 339.14 100.48 341.64 109.76 C 332.40 112.91 323.05 115.67 313.82 118.83 C 312.45 112.84 313.85 105.94 319.20 102.34 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 504.21 109.50 C 506.56 104.46 511.11 99.98 516.95 99.70 C 523.27 98.92 529.72 102.96 531.95 108.89 C 533.26 112.04 532.85 115.54 532.35 118.82 C 522.97 115.69 513.49 112.88 504.21 109.50 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 203.76 130.01 C 197.68 123.29 201.08 111.49 209.27 108.17 C 215.24 106.07 223.90 106.86 226.91 113.29 C 219.04 118.65 211.42 124.35 203.76 130.01 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 619.09 112.97 C 624.56 104.43 639.30 105.34 643.64 114.53 C 646.57 119.31 645.66 125.21 643.05 129.91 C 634.66 124.91 627.06 118.63 619.09 112.97 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 284.08 117.01 C 287.20 111.28 294.47 108.38 300.70 110.22 C 305.23 111.52 309.30 115.08 310.38 119.78 C 301.15 122.97 291.89 126.08 282.52 128.84 C 282.38 124.88 281.62 120.47 284.08 117.01 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 542.99 111.12 C 549.53 107.85 558.45 110.35 561.96 116.87 C 564.23 120.47 563.86 124.91 563.29 128.93 C 554.07 125.48 544.30 123.48 535.39 119.26 C 537.24 116.02 539.42 112.66 542.99 111.12 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 230.22 121.23 C 234.00 116.37 240.94 114.07 246.77 116.38 C 249.63 117.26 251.71 119.49 253.67 121.64 C 245.72 127.25 237.93 133.07 230.00 138.71 C 226.16 133.72 226.22 126.11 230.22 121.23 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 595.56 118.48 C 601.19 113.96 610.06 114.73 614.94 120.01 C 619.65 124.91 619.99 133.16 616.22 138.70 C 608.60 133.35 601.07 127.87 593.56 122.37 C 592.43 120.67 594.38 119.39 595.56 118.48 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 398.41 119.44 C 411.54 117.94 424.80 118.57 437.99 118.61 C 479.17 120.63 519.91 131.59 556.49 150.64 C 588.65 167.38 617.74 190.11 641.49 217.51 C 680.99 262.57 706.06 320.21 711.40 379.94 C 713.08 393.55 712.48 407.30 712.44 420.99 C 710.63 460.20 700.66 499.03 683.33 534.27 C 667.16 567.15 644.73 596.99 617.51 621.52 C 570.61 664.23 509.25 690.84 445.96 695.42 C 440.60 695.31 435.36 696.65 430.00 696.42 C 423.66 696.31 417.29 696.68 410.96 696.16 C 407.35 695.53 403.68 695.48 400.02 695.38 C 359.41 692.08 319.52 680.06 283.89 660.27 C 250.94 642.05 221.69 617.27 198.09 587.96 C 170.69 553.86 151.04 513.47 141.57 470.75 C 126.58 405.39 135.54 334.89 166.44 275.34 C 191.13 227.31 229.52 186.47 275.95 158.89 C 313.09 136.74 355.29 122.94 398.41 119.44 M 395.40 133.28 C 328.60 139.65 264.88 172.19 219.95 221.92 C 181.80 263.44 156.92 317.05 150.14 373.04 C 149.33 378.33 149.13 383.69 148.46 389.00 C 148.31 402.98 147.64 417.05 149.03 430.99 C 153.69 488.01 177.09 543.23 214.45 586.53 C 239.28 615.45 270.10 639.25 304.49 655.72 C 353.94 679.73 410.68 687.98 464.95 679.73 C 506.60 673.56 546.68 657.41 581.16 633.27 C 612.55 611.32 639.38 582.82 659.28 550.08 C 681.94 512.97 695.56 470.36 698.56 427.00 C 698.87 414.00 698.88 401.00 698.57 388.01 C 695.07 334.74 675.26 282.71 642.76 240.36 C 620.10 210.65 591.37 185.60 558.82 167.25 C 523.74 147.37 484.20 135.41 443.99 132.50 C 433.34 132.23 422.67 132.04 412.01 132.31 C 406.47 132.50 400.88 132.25 395.40 133.28 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 566.05 130.06 C 571.27 122.86 583.09 122.28 588.84 129.13 C 593.32 133.89 593.25 141.29 590.43 146.89 C 587.40 146.33 585.14 144.14 582.72 142.41 C 577.20 138.24 571.37 134.48 566.05 130.06 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 235.68 144.74 C 241.93 141.78 249.39 144.07 253.88 149.07 C 246.10 155.09 238.17 160.96 229.96 166.39 C 224.50 159.50 227.60 148.11 235.68 144.74 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 592.57 149.21 C 597.44 142.56 607.91 141.47 613.99 147.03 C 619.62 151.83 620.04 160.70 616.21 166.73 C 608.42 160.77 600.07 155.53 592.57 149.21 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 208.31 164.43 C 214.40 160.77 223.31 162.57 227.13 168.66 C 219.40 174.45 211.54 180.05 203.73 185.72 C 198.26 179.14 200.86 168.30 208.31 164.43 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 619.04 168.63 C 623.64 161.22 635.28 160.57 641.07 166.94 C 646.11 171.76 646.92 180.35 642.34 185.74 C 634.64 179.95 626.65 174.55 619.04 168.63 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 178.31 199.98 C 177.67 191.72 185.77 184.20 193.97 185.29 C 196.32 185.49 200.56 185.79 200.78 188.74 C 195.35 196.54 189.73 204.23 184.00 211.81 C 180.97 208.58 177.85 204.70 178.31 199.98 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 644.83 187.91 C 652.77 181.50 666.34 186.92 667.54 197.09 C 668.50 202.55 666.51 208.22 662.01 211.54 C 656.07 203.82 650.27 195.98 644.83 187.91 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 700.58 187.93 C 703.87 184.84 708.59 184.90 712.79 185.48 C 720.57 187.40 725.59 196.39 723.02 204.00 C 722.01 206.97 719.96 209.36 717.96 211.71 C 711.92 203.98 706.22 195.96 700.58 187.93 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 138.50 213.50 C 143.44 210.26 149.66 211.27 154.53 214.07 C 148.78 222.10 143.02 230.13 137.08 238.02 C 129.00 232.21 129.38 218.07 138.50 213.50 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 167.25 213.11 C 171.98 210.32 177.68 211.52 182.19 214.10 C 176.97 222.31 170.69 229.79 165.33 237.91 C 156.22 232.59 157.50 217.03 167.25 213.11 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 692.08 213.73 C 697.26 210.85 703.84 210.56 708.76 214.17 C 716.93 219.41 716.71 232.39 709.04 238.02 C 704.11 231.55 699.46 224.87 694.60 218.35 C 693.52 216.95 692.62 215.41 692.08 213.73 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 146.24 240.42 C 151.26 237.05 158.13 237.06 162.99 240.75 C 157.80 248.30 152.21 255.58 146.93 263.07 C 146.42 264.17 144.64 263.81 144.03 263.01 C 138.15 256.79 138.83 245.17 146.24 240.42 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 683.11 240.69 C 689.84 235.58 700.54 237.91 704.43 245.42 C 708.14 251.62 706.14 260.24 700.25 264.35 C 694.46 256.52 688.61 248.72 683.11 240.69 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 103.19 279.19 C 106.91 274.98 112.70 274.91 117.86 275.47 C 115.27 284.84 111.95 294.00 108.98 303.26 C 98.59 300.98 95.43 286.09 103.19 279.19 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 728.23 275.47 C 731.96 275.44 736.10 274.56 739.46 276.66 C 744.69 279.19 747.74 285.24 747.39 290.93 C 746.51 296.37 742.95 302.22 737.08 303.15 C 734.08 293.94 730.88 284.78 728.23 275.47 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 755.22 283.70 C 761.18 282.74 767.80 284.60 771.24 289.86 C 776.89 297.28 772.85 309.63 763.70 311.92 C 761.38 305.68 759.68 299.24 757.44 292.98 C 756.39 289.97 755.22 286.93 755.22 283.70 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 72.43 298.00 C 71.90 288.43 82.71 280.86 91.59 284.32 C 88.25 293.50 85.60 302.92 82.26 312.10 C 76.51 309.96 71.98 304.32 72.43 298.00 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 125.78 298.05 C 128.49 297.26 131.34 297.59 134.08 298.03 C 131.83 307.51 128.31 316.63 125.34 325.90 C 119.39 324.24 114.97 318.17 115.41 311.99 C 114.99 305.68 119.73 299.61 125.78 298.05 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 712.30 297.68 C 717.75 297.04 723.83 298.05 727.43 302.61 C 734.06 309.95 730.51 323.44 720.72 325.89 C 718.08 318.05 715.66 310.14 712.98 302.31 C 712.41 300.83 712.38 299.23 712.30 297.68 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 96.57 307.69 C 99.97 305.71 104.07 306.36 107.80 306.59 C 105.03 315.70 102.31 324.89 98.83 333.76 C 95.38 334.08 92.59 330.93 90.85 328.25 C 86.37 321.44 89.18 311.17 96.57 307.69 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 738.24 306.70 C 741.67 306.32 745.37 305.79 748.63 307.26 C 754.36 309.51 757.92 315.93 757.43 321.95 C 756.81 327.57 752.92 332.35 747.75 334.52 C 745.65 330.94 744.87 326.82 743.51 322.94 C 741.63 317.57 740.00 312.11 738.24 306.70 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 107.39 335.38 C 110.59 329.69 117.77 327.44 123.93 328.85 C 121.99 338.46 118.09 347.55 115.31 356.94 C 106.35 354.66 102.44 342.89 107.39 335.38 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 722.36 328.66 C 729.18 327.34 736.98 330.46 739.69 337.14 C 743.14 344.74 739.03 354.64 730.87 356.99 C 728.95 351.04 726.90 345.15 725.05 339.18 C 724.04 335.70 722.25 332.37 722.36 328.66 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 101.76 400.61 C 104.23 395.97 109.12 392.72 114.48 392.89 C 114.66 402.62 114.64 412.35 114.48 422.07 C 108.06 421.69 101.99 417.16 100.56 410.78 C 100.32 407.39 99.88 403.64 101.76 400.61 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 776.55 393.01 C 785.91 392.15 793.68 402.69 790.50 411.37 C 788.94 417.55 782.83 422.08 776.47 421.86 C 776.46 412.24 776.30 402.62 776.55 393.01 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 101.97 432.92 C 104.34 428.28 109.36 425.43 114.51 425.35 C 114.61 435.15 114.67 444.96 114.47 454.76 C 107.93 454.30 101.61 449.57 100.50 442.93 C 100.27 439.55 100.01 435.87 101.97 432.92 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 90.06 500.18 C 86.13 492.58 90.75 482.67 98.75 480.14 C 101.29 486.64 102.98 493.44 105.36 500.00 C 106.34 502.72 107.18 505.50 107.71 508.36 C 100.79 509.79 93.09 506.80 90.06 500.18 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 743.64 491.34 C 744.93 487.55 745.74 483.55 747.75 480.04 C 752.66 482.29 756.53 486.73 757.39 492.14 C 758.24 498.51 754.23 505.09 748.31 507.49 C 745.24 509.14 741.66 508.40 738.36 508.34 C 739.74 502.56 741.76 496.97 743.64 491.34 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 720.94 488.34 C 726.53 491.01 731.34 496.40 730.80 502.97 C 731.04 512.27 720.81 519.51 712.09 516.63 C 714.22 506.99 717.93 497.74 720.94 488.34 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 761.93 507.62 C 762.58 505.97 762.80 502.32 765.46 503.39 C 773.83 506.80 776.61 518.84 770.58 525.60 C 767.00 530.28 760.61 532.19 754.98 530.64 C 756.51 522.75 759.94 515.39 761.93 507.62 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 99.23 522.95 C 99.23 517.40 103.95 513.09 108.75 511.08 C 112.12 520.35 115.13 529.78 117.84 539.26 C 111.60 540.81 104.66 538.42 101.12 532.96 C 98.85 530.13 99.15 526.35 99.23 522.95 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 737.30 511.09 C 744.45 513.54 749.45 522.09 746.59 529.39 C 744.44 536.92 735.68 541.47 728.23 539.09 C 730.99 529.67 734.13 520.37 737.30 511.09 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 237.53 547.45 C 241.18 543.43 242.79 538.13 244.15 533.00 C 245.38 540.36 249.11 547.45 255.27 551.84 C 258.69 554.49 262.86 555.79 266.97 556.97 C 262.26 559.05 257.06 560.51 253.33 564.27 C 248.11 568.74 245.12 575.22 244.07 581.93 C 243.01 575.19 239.99 568.67 234.75 564.18 C 230.90 560.43 225.63 558.96 220.81 556.93 C 227.21 555.64 233.37 552.59 237.53 547.45 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 579.73 556.98 C 591.36 555.26 600.73 545.69 602.97 534.27 C 604.97 538.74 606.34 543.64 609.62 547.41 C 613.86 552.51 620.01 555.64 626.44 556.96 C 621.08 559.09 615.29 560.87 611.32 565.32 C 606.99 569.20 605.17 574.83 602.97 580.02 C 601.35 573.55 598.12 567.27 592.73 563.16 C 588.98 560.01 584.18 558.76 579.73 556.98 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 145.46 573.55 C 138.17 568.16 138.21 555.39 145.89 550.36 C 149.57 554.98 152.84 559.90 156.37 564.63 C 158.62 567.80 161.33 570.71 162.86 574.35 C 157.52 577.25 150.32 577.61 145.46 573.55 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 683.26 574.15 C 688.38 565.84 694.54 558.21 700.24 550.28 C 703.91 553.01 706.39 557.34 706.32 561.99 C 706.45 567.26 703.24 572.20 698.78 574.83 C 693.99 577.46 687.83 577.06 683.26 574.15 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 131.36 588.99 C 131.15 584.40 132.98 578.98 137.45 577.00 C 143.24 584.71 148.62 592.72 154.60 600.29 C 150.71 603.19 145.65 603.09 141.07 602.40 C 135.61 600.38 131.08 595.01 131.36 588.99 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 159.30 589.03 C 158.90 584.44 160.79 578.75 165.43 577.04 C 170.87 584.98 177.21 592.36 182.05 600.68 C 178.01 603.07 173.10 603.14 168.62 602.25 C 163.43 600.09 158.85 594.94 159.30 589.03 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 678.73 579.63 C 679.55 578.49 680.78 576.38 682.41 577.63 C 687.97 582.67 688.79 591.99 683.75 597.69 C 679.25 603.67 670.17 604.27 664.07 600.56 C 668.31 593.16 674.07 586.76 678.73 579.63 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 708.53 577.44 C 710.49 576.76 711.41 579.18 712.49 580.37 C 715.15 583.86 715.13 588.52 714.44 592.66 C 713.04 597.11 709.43 600.79 705.05 602.40 C 700.60 603.05 695.75 603.17 691.87 600.56 C 694.68 595.59 698.50 591.30 701.68 586.57 C 704.00 583.55 705.96 580.25 708.53 577.44 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 179.06 609.76 C 180.07 607.10 182.00 604.96 184.03 603.01 C 188.60 608.50 192.49 614.51 196.81 620.20 C 198.39 622.47 200.57 624.55 200.91 627.45 C 195.69 629.94 189.07 630.43 184.30 626.69 C 178.93 623.04 176.89 615.79 179.06 609.76 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 647.99 621.97 C 652.77 615.75 657.11 609.20 661.97 603.04 C 669.71 608.45 669.69 621.48 661.82 626.76 C 656.96 630.40 650.32 629.97 645.10 627.36 C 645.60 625.34 646.72 623.58 647.99 621.97 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 122.57 613.95 C 122.63 609.65 125.28 606.11 128.13 603.14 C 130.93 606.00 133.06 609.40 135.43 612.60 C 138.85 617.39 142.62 621.95 145.51 627.11 C 142.58 628.64 139.37 629.96 135.99 629.55 C 128.25 629.16 121.73 621.70 122.57 613.95 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 151.16 610.06 C 152.13 607.31 154.08 605.09 156.09 603.05 C 160.71 608.50 164.60 614.51 168.89 620.22 C 170.51 622.48 172.60 624.62 172.98 627.51 C 167.78 630.07 161.11 630.49 156.40 626.68 C 151.12 623.10 149.14 616.00 151.16 610.06 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 705.59 619.58 C 709.78 614.15 713.37 608.25 717.97 603.14 C 720.81 606.09 723.57 609.71 723.59 614.01 C 724.28 621.38 718.34 628.57 711.01 629.47 C 707.55 630.04 704.17 628.87 701.01 627.60 C 701.36 624.38 703.86 622.12 705.59 619.58 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 213.95 651.70 C 203.11 651.74 196.65 637.06 203.75 628.95 C 211.46 634.38 218.97 640.09 226.71 645.48 C 226.64 646.00 226.50 647.03 226.44 647.55 C 222.95 650.51 218.60 652.39 213.95 651.70 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 619.38 645.55 C 627.23 640.13 634.65 634.06 642.74 629.00 C 645.35 632.82 645.03 637.64 644.53 642.03 C 642.75 648.17 636.37 652.52 629.98 651.73 C 625.97 652.13 622.61 649.78 619.62 647.45 C 619.56 646.98 619.44 646.03 619.38 645.55 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 229.95 648.10 C 237.92 653.58 245.74 659.29 253.44 665.15 C 248.81 672.71 237.04 673.26 231.31 666.67 C 226.30 661.90 225.96 653.59 229.95 648.10 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 605.62 655.61 C 609.18 653.06 612.54 650.18 616.44 648.14 C 620.11 654.46 619.48 663.66 613.28 668.19 C 607.08 673.21 596.89 672.02 592.62 665.11 C 596.81 661.76 601.32 658.83 605.62 655.61 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 258.94 687.04 C 253.16 682.36 251.57 673.07 256.58 667.25 C 264.40 673.02 272.38 678.56 280.06 684.50 C 275.38 691.11 265.02 692.46 258.94 687.04 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 577.86 675.77 C 581.88 672.89 585.70 669.67 590.08 667.33 C 591.34 670.05 592.62 672.92 592.41 676.00 C 592.67 683.69 585.62 690.54 578.00 690.42 C 573.33 690.66 569.20 687.96 566.05 684.76 C 569.63 681.31 573.92 678.76 577.86 675.77 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 228.97 676.42 C 231.54 676.37 233.37 678.36 235.36 679.69 C 241.31 684.27 247.63 688.36 253.44 693.13 C 250.54 697.43 245.11 699.65 240.03 698.98 C 232.80 698.28 226.61 691.30 227.26 683.98 C 227.17 681.34 228.25 678.89 228.97 676.42 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 610.16 680.16 C 612.30 678.66 614.28 676.68 616.98 676.28 C 619.20 681.85 619.82 688.95 615.63 693.78 C 610.14 700.95 597.63 700.71 592.62 693.12 C 598.28 688.55 604.38 684.57 610.16 680.16 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 202.73 685.09 C 206.04 685.58 208.37 688.20 211.04 689.96 C 216.32 694.06 222.03 697.60 227.10 701.97 C 224.28 705.10 220.42 707.79 216.04 707.69 C 209.02 708.39 202.31 702.81 200.97 696.02 C 199.94 692.27 201.39 688.55 202.73 685.09 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 632.78 691.69 C 636.10 689.30 639.25 686.63 642.92 684.76 C 644.01 687.05 645.32 689.36 645.48 691.96 C 646.01 698.33 641.80 704.61 635.91 706.92 C 629.85 709.22 623.03 706.83 618.96 701.98 C 623.30 698.21 628.18 695.12 632.78 691.69 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 313.59 696.13 C 323.15 698.36 332.34 701.99 341.71 704.92 C 340.18 709.23 336.89 713.01 332.36 714.22 C 325.63 716.82 317.45 713.07 314.55 706.56 C 312.85 703.35 313.53 699.60 313.59 696.13 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 290.97 712.49 C 300.47 714.76 309.61 718.34 318.93 721.28 C 318.21 725.65 314.55 728.84 310.61 730.41 C 303.96 733.51 295.57 729.89 292.29 723.56 C 290.40 720.19 290.64 716.19 290.97 712.49 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 527.84 720.96 C 536.68 718.11 545.56 715.33 554.35 712.32 C 558.53 720.65 550.72 730.96 541.93 731.49 C 536.70 731.84 531.17 729.11 528.42 724.61 C 527.88 723.47 526.60 722.08 527.84 720.96 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 441.28 715.46 C 450.96 715.40 460.63 715.44 470.31 715.44 C 470.64 724.19 461.72 731.73 453.20 729.92 C 446.49 728.73 440.77 722.45 441.28 715.46 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 408.42 715.50 C 418.19 715.39 427.96 715.39 437.73 715.50 C 437.73 721.95 432.98 728.18 426.63 729.60 C 417.91 732.38 408.12 724.63 408.42 715.50 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 322.42 722.47 C 331.60 725.00 340.45 728.63 349.70 730.92 C 349.80 735.68 345.37 738.97 341.37 740.60 C 334.12 743.75 325.17 739.18 322.56 731.92 C 321.96 728.80 322.23 725.61 322.42 722.47 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 496.12 731.41 C 505.44 728.33 514.68 724.87 524.22 722.54 C 525.41 729.14 522.92 736.67 516.62 739.76 C 509.26 744.31 498.12 739.89 496.12 731.41 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 425.11 738.04 C 434.73 737.75 444.41 737.48 454.01 738.21 C 453.98 745.69 447.57 752.59 440.02 752.68 C 432.16 753.24 424.24 746.13 425.11 738.04 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 299.61 739.05 C 304.27 739.72 308.58 741.71 313.06 743.06 C 318.00 744.59 322.92 746.20 327.78 747.95 C 326.20 751.90 323.31 755.42 319.25 756.97 C 313.67 758.96 306.87 757.70 302.96 753.05 C 299.22 749.41 299.10 743.89 299.61 739.05 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 533.64 742.86 C 537.93 741.54 542.09 739.66 546.58 739.07 C 546.64 742.62 547.32 746.48 545.49 749.73 C 542.90 754.58 537.71 758.39 532.01 757.80 C 525.76 758.23 520.56 753.46 518.26 748.01 C 523.32 746.11 528.48 744.47 533.64 742.86 Z\"><\/path><path fill=\"#025331\" opacity=\"1.00\" d=\" M 408.44 760.58 C 418.19 760.47 427.95 760.47 437.71 760.58 C 438.03 769.90 427.56 778.02 418.70 774.54 C 412.66 772.79 408.42 766.83 408.44 760.58 Z\"><\/path><\/g><g id=\"#fefefeff\"><\/g><g id=\"#035331ff\"><path fill=\"#035331\" opacity=\"1.00\" d=\" M 415.34 41.44 C 418.66 39.18 422.86 39.24 426.68 39.74 C 433.02 41.19 437.78 47.30 437.83 53.77 C 432.95 54.76 427.94 54.18 423.00 54.32 C 418.10 54.16 413.13 54.79 408.31 53.73 C 408.61 48.83 410.94 43.91 415.34 41.44 Z\"><\/path><path fill=\"#035331\" opacity=\"1.00\" d=\" M 300.47 65.36 C 302.56 60.37 307.72 57.08 313.01 56.59 C 319.47 56.23 325.82 60.63 327.72 66.83 C 318.44 69.81 309.21 72.98 299.87 75.80 C 299.36 72.34 298.94 68.62 300.47 65.36 Z\"><\/path><path fill=\"#035331\" opacity=\"1.00\" d=\" M 324.82 78.71 C 331.12 69.72 347.72 72.28 349.99 83.37 C 340.73 86.07 331.77 89.76 322.37 91.92 C 322.09 87.41 321.59 82.36 324.82 78.71 Z\"><\/path><path fill=\"#035331\" opacity=\"1.00\" d=\" M 296.84 85.87 C 304.22 80.34 316.98 84.01 318.95 93.41 C 309.77 96.46 300.49 99.23 291.39 102.52 C 289.58 96.51 291.51 89.43 296.84 85.87 Z\"><\/path><path fill=\"#035331\" opacity=\"1.00\" d=\" M 414.20 87.35 C 417.84 84.44 422.82 84.05 427.23 85.01 C 433.42 86.67 437.92 92.83 437.82 99.20 C 428.00 99.50 418.12 99.67 408.31 99.11 C 408.56 94.59 410.39 90.01 414.20 87.35 Z\"><\/path><path fill=\"#035331\" opacity=\"1.00\" d=\" M 255.24 132.30 C 259.21 122.65 274.71 121.36 279.95 130.45 C 272.85 135.49 265.80 140.61 258.82 145.82 C 257.91 146.25 257.08 147.57 255.96 147.02 C 253.39 142.55 252.52 136.92 255.24 132.30 Z\"><\/path><path fill=\"#035331\" opacity=\"1.00\" d=\" M 385.17 204.25 C 410.98 204.28 436.80 204.10 462.61 204.34 C 470.28 215.64 478.12 226.83 485.77 238.15 C 481.57 244.09 476.49 249.32 471.92 254.96 C 456.82 272.90 441.65 290.78 426.59 308.76 C 425.64 309.84 424.63 310.87 423.60 311.88 C 402.81 287.36 382.12 262.75 361.42 238.16 C 369.66 227.09 376.91 215.31 385.17 204.25 M 394.88 212.68 C 398.06 218.60 401.73 224.24 405.14 230.03 C 409.07 224.48 412.60 218.63 415.92 212.70 C 408.91 212.55 401.89 212.56 394.88 212.68 M 431.80 212.66 C 433.84 217.51 437.01 221.75 439.65 226.28 C 440.33 227.56 441.44 228.50 442.62 229.31 C 445.73 223.71 449.73 218.60 452.21 212.67 C 445.41 212.56 438.60 212.58 431.80 212.66 M 374.98 233.73 C 382.58 233.84 390.19 233.82 397.80 233.74 C 394.20 227.87 390.65 221.96 387.01 216.11 C 382.88 221.90 378.88 227.78 374.98 233.73 M 460.38 216.21 C 456.87 222.04 453.13 227.74 449.85 233.72 C 457.34 233.91 464.85 233.89 472.34 233.73 C 468.63 227.71 464.64 221.85 460.38 216.21 M 413.05 233.75 C 420.14 233.86 427.23 233.85 434.32 233.76 C 431.08 227.92 427.47 222.29 423.83 216.69 C 419.82 222.10 416.50 227.98 413.05 233.75 M 376.32 242.55 C 384.01 252.52 392.52 261.81 400.48 271.55 C 405.00 276.71 409.08 282.27 413.99 287.06 C 410.51 272.09 406.21 257.31 402.19 242.47 C 393.57 242.42 384.94 242.26 376.32 242.55 M 411.15 242.53 C 414.85 258.16 419.44 273.57 423.63 289.08 C 428.57 273.74 432.22 258.02 436.72 242.56 C 428.20 242.40 419.67 242.44 411.15 242.53 M 443.58 248.50 C 440.19 261.69 436.15 274.71 433.10 287.99 C 445.67 272.79 458.83 258.05 471.06 242.58 C 462.56 242.19 454.06 242.54 445.56 242.37 C 444.76 244.36 444.09 246.41 443.58 248.50 Z\"><\/path><path fill=\"#035331\" opacity=\"1.00\" d=\" M 77.64 391.00 C 77.29 383.26 84.22 376.58 91.79 376.31 C 92.87 386.01 92.04 395.84 92.26 405.60 C 84.51 405.87 77.28 398.81 77.64 391.00 Z\"><\/path><path fill=\"#035331\" opacity=\"1.00\" d=\" M 57.37 399.36 C 59.88 395.20 64.58 392.77 69.42 392.95 C 69.57 402.66 69.56 412.38 69.42 422.10 C 63.30 421.71 57.54 417.65 55.59 411.77 C 55.11 407.61 54.65 402.89 57.37 399.36 Z\"><\/path><path fill=\"#035331\" opacity=\"1.00\" d=\" M 731.35 393.07 C 734.22 393.12 737.26 393.29 739.55 395.27 C 745.77 399.15 747.50 407.85 744.30 414.21 C 741.67 418.81 736.72 421.89 731.39 421.95 C 731.27 412.32 731.32 402.70 731.35 393.07 Z\"><\/path><path fill=\"#035331\" opacity=\"1.00\" d=\" M 73.59 510.43 C 75.21 506.62 78.79 504.21 82.30 502.29 C 85.45 511.68 88.35 521.16 91.61 530.51 C 86.54 531.95 80.72 530.92 76.95 527.09 C 72.23 523.10 71.27 515.94 73.59 510.43 Z\"><\/path><\/g><g id=\"#035332ff\"><path fill=\"#035332\" opacity=\"1.00\" d=\" M 346.82 95.70 C 350.86 89.74 359.52 87.81 365.79 91.26 C 369.05 92.99 371.14 96.16 372.91 99.29 C 363.75 102.98 354.17 105.50 344.83 108.71 C 343.95 104.33 344.10 99.45 346.82 95.70 Z\"><\/path><path fill=\"#035332\" opacity=\"1.00\" d=\" M 134.28 267.57 C 137.28 266.05 140.72 266.61 143.94 266.61 C 142.35 276.33 138.27 285.46 135.41 294.86 C 129.49 293.14 125.06 287.20 125.44 281.00 C 125.17 275.27 128.97 269.66 134.28 267.57 Z\"><\/path><path fill=\"#035332\" opacity=\"1.00\" d=\" M 731.36 389.45 C 731.42 379.67 731.07 369.89 731.53 360.12 C 737.52 360.15 743.19 364.14 745.15 369.81 C 746.45 374.29 746.03 379.50 743.20 383.34 C 740.50 387.12 735.86 389.03 731.36 389.45 Z\"><\/path><path fill=\"#035332\" opacity=\"1.00\" d=\" M 731.38 425.33 C 737.30 425.35 743.11 429.14 745.02 434.84 C 747.56 441.02 744.96 448.89 739.14 452.26 C 736.87 453.71 734.21 454.34 731.61 454.88 C 731.01 445.05 731.42 435.18 731.38 425.33 Z\"><\/path><path fill=\"#035332\" opacity=\"1.00\" d=\" M 497.83 541.58 C 510.54 538.94 523.70 540.48 536.33 542.78 C 536.56 549.95 537.20 557.11 537.09 564.29 C 535.63 564.41 534.19 564.54 532.75 564.68 C 530.67 559.44 528.50 553.64 523.43 550.57 C 516.13 545.94 507.14 547.35 498.96 547.46 C 488.39 549.27 478.04 555.34 473.00 565.08 C 467.83 574.17 467.52 585.11 468.93 595.24 C 470.35 605.56 475.88 615.88 485.44 620.74 C 498.01 627.66 513.18 625.86 526.47 622.21 C 526.81 615.80 526.57 609.37 526.51 602.96 C 526.50 600.03 525.78 596.64 523.23 594.87 C 520.42 593.45 517.19 593.66 514.14 593.53 C 513.97 592.32 513.82 591.11 513.68 589.90 C 519.12 589.64 524.57 589.70 530.00 590.10 C 536.08 590.52 542.14 589.66 548.23 589.73 C 548.27 590.59 548.36 592.30 548.41 593.16 C 544.98 593.65 540.53 594.36 539.76 598.45 C 539.08 605.93 539.67 613.48 539.26 620.98 C 539.28 622.37 538.00 623.40 536.85 623.95 C 521.95 630.65 505.27 632.78 489.07 631.23 C 480.32 629.78 471.89 625.73 465.92 619.08 C 460.09 613.10 456.90 605.01 455.49 596.90 C 455.27 589.59 454.37 581.90 457.31 574.99 C 463.47 557.49 480.25 545.67 497.83 541.58 Z\"><\/path><path fill=\"#035332\" opacity=\"1.00\" d=\" M 344.68 541.60 C 352.43 542.17 360.26 542.90 368.01 541.72 C 381.76 541.07 395.82 540.76 409.18 544.58 C 419.36 547.28 429.38 552.92 434.85 562.23 C 441.21 572.64 441.59 585.60 439.40 597.29 C 437.16 610.05 427.90 621.10 415.90 625.86 C 402.11 631.96 386.70 630.75 372.01 630.60 C 363.13 630.29 354.24 630.69 345.36 630.71 C 345.32 629.63 345.29 628.56 345.26 627.50 C 348.31 627.03 351.38 626.69 354.42 626.21 C 356.62 625.10 357.50 622.40 357.45 620.08 C 357.65 600.06 357.69 580.03 357.47 560.00 C 357.45 555.58 357.19 550.92 355.05 546.96 C 351.67 545.58 347.87 545.84 344.29 545.37 C 344.39 544.43 344.58 542.54 344.68 541.60 M 370.42 547.41 C 370.19 572.69 370.20 597.98 370.47 623.26 C 382.15 625.60 394.73 626.29 405.97 621.67 C 415.01 618.16 422.19 610.32 425.06 601.07 C 427.36 594.99 426.69 588.38 426.75 582.02 C 427.07 570.01 420.30 557.89 409.39 552.58 C 397.38 546.32 383.52 547.13 370.42 547.41 Z\"><\/path><path fill=\"#035332\" opacity=\"1.00\" d=\" M 201.47 669.75 C 199.70 665.27 201.12 660.32 203.69 656.47 C 210.48 662.10 217.91 666.89 224.96 672.17 C 225.77 672.83 226.40 673.69 227.05 674.51 C 224.23 677.09 220.98 679.62 216.97 679.73 C 210.25 680.70 203.32 676.30 201.47 669.75 Z\"><\/path><path fill=\"#035332\" opacity=\"1.00\" d=\" M 344.64 706.23 C 350.38 707.27 355.78 709.60 361.36 711.26 C 365.21 712.72 369.44 713.32 372.91 715.66 C 370.75 719.09 368.29 722.78 364.20 724.03 C 356.87 727.43 347.26 722.83 344.99 715.14 C 344.02 712.26 344.38 709.18 344.64 706.23 Z\"><\/path><path fill=\"#035332\" opacity=\"1.00\" d=\" M 392.25 738.18 C 396.81 737.59 401.42 737.85 406.01 737.82 C 411.26 737.88 416.55 737.47 421.76 738.39 C 420.86 744.24 417.35 749.89 411.55 751.88 C 402.61 755.51 391.75 747.83 392.25 738.18 Z\"><\/path><\/g><g id=\"#025332ff\"><path fill=\"#025332\" opacity=\"1.00\" d=\" M 206.71 137.56 C 212.86 132.75 222.86 134.20 227.15 140.81 C 219.40 146.61 211.42 152.09 203.70 157.93 C 198.70 151.85 200.30 142.00 206.71 137.56 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 619.34 140.77 C 620.75 137.11 625.36 135.42 629.02 134.81 C 637.33 133.51 645.31 140.74 645.46 149.00 C 645.64 152.18 644.13 155.08 642.77 157.85 C 637.13 154.40 632.02 150.18 626.62 146.38 C 624.18 144.53 621.39 143.07 619.34 140.77 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 122.87 202.86 C 121.04 195.50 125.93 187.42 133.21 185.49 C 137.44 184.84 142.12 184.90 145.52 187.88 C 140.11 195.95 134.11 203.60 128.59 211.59 C 125.97 209.24 123.44 206.48 122.87 202.86 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 155.57 188.52 C 160.45 184.27 168.32 183.96 173.47 187.90 C 168.01 195.78 162.28 203.46 156.64 211.21 C 148.49 206.80 148.52 193.95 155.57 188.52 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 672.42 187.97 C 679.45 182.54 690.78 185.26 694.39 193.46 C 697.60 199.77 694.93 207.23 690.01 211.81 C 684.00 203.97 678.43 195.80 672.42 187.97 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 664.03 214.13 C 666.00 213.18 667.98 212.15 670.13 211.64 C 677.17 210.53 684.85 215.18 686.50 222.25 C 688.61 227.97 685.69 234.38 681.11 238.01 C 675.39 230.07 669.24 222.41 664.03 214.13 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 701.57 266.72 C 707.47 265.76 714.13 267.03 717.83 272.14 C 723.86 279.62 720.16 292.46 710.64 294.87 C 707.55 285.51 704.44 276.15 701.57 266.72 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 101.47 380.78 C 97.08 371.79 104.25 359.68 114.54 360.24 C 114.56 370.04 114.73 379.85 114.43 389.65 C 109.11 388.70 103.63 386.07 101.47 380.78 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 754.17 376.31 C 761.55 376.48 768.16 382.57 768.60 389.98 C 769.27 398.11 762.00 406.02 753.75 405.62 C 753.96 395.86 753.19 386.03 754.17 376.31 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 77.64 424.00 C 77.05 416.12 84.17 408.68 92.10 409.24 C 92.51 417.49 92.17 425.76 92.31 434.02 C 92.10 435.46 92.76 437.70 91.01 438.41 C 83.92 437.45 77.44 431.46 77.64 424.00 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 753.88 409.22 C 762.28 408.59 769.53 416.77 768.58 424.98 C 767.90 432.40 761.18 438.15 753.86 438.45 C 753.67 428.71 753.61 418.96 753.88 409.22 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 105.69 467.26 C 107.24 462.98 110.66 458.65 115.43 458.03 C 118.16 467.26 121.92 476.21 123.97 485.64 C 118.31 487.10 111.95 485.33 108.35 480.60 C 105.01 477.01 104.99 471.81 105.69 467.26 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 730.65 458.07 C 738.61 459.30 742.71 469.03 740.17 476.24 C 737.94 483.62 729.40 487.74 722.11 485.66 C 724.19 476.26 727.93 467.30 730.65 458.07 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 116.85 509.20 C 112.83 501.82 116.80 490.63 125.48 489.06 C 127.36 494.39 128.91 499.83 130.77 505.17 C 131.96 509.01 133.61 512.78 133.83 516.85 C 127.30 518.46 119.88 515.27 116.85 509.20 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 125.45 534.00 C 124.97 527.77 129.36 521.32 135.54 519.93 C 138.47 529.05 141.59 538.10 144.27 547.30 C 135.78 551.07 125.09 543.10 125.45 534.00 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 710.56 519.96 C 717.74 521.47 722.05 529.65 720.46 536.59 C 719.04 544.53 709.56 550.70 701.93 547.29 C 704.38 538.06 707.70 529.08 710.56 519.96 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 299.32 541.81 C 310.20 542.03 321.17 542.98 332.05 541.83 C 333.59 541.69 335.14 541.73 336.69 541.79 C 336.67 543.02 336.66 544.26 336.66 545.50 C 333.32 545.54 329.99 545.90 326.75 546.69 C 325.49 549.96 324.84 553.44 324.79 556.95 C 324.44 576.30 324.59 595.64 324.68 614.99 C 324.85 618.68 324.25 623.09 326.99 626.02 C 330.16 626.92 333.47 627.26 336.74 627.55 C 336.74 628.61 336.74 629.67 336.74 630.73 C 324.50 630.37 312.26 630.53 300.02 630.69 C 298.04 631.23 298.14 627.07 300.06 627.49 C 303.73 626.61 309.07 627.86 311.08 623.84 C 311.91 619.61 311.59 615.27 311.73 610.99 C 311.76 593.33 311.93 575.67 311.59 558.02 C 311.43 554.21 311.78 549.96 309.30 546.76 C 306.15 545.43 302.66 545.71 299.33 545.53 C 299.33 544.28 299.32 543.04 299.32 541.81 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 672.40 626.95 C 678.23 618.97 683.79 610.78 689.96 603.06 C 693.10 605.89 695.68 609.68 695.72 614.06 C 696.46 621.82 689.77 629.23 682.03 629.50 C 678.59 629.88 675.41 628.38 672.40 626.95 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 635.03 662.11 C 637.64 660.26 640.04 657.90 643.23 657.12 C 645.94 662.25 646.37 668.73 642.76 673.56 C 637.85 681.48 625.14 681.92 619.49 674.62 C 619.50 674.33 619.52 673.75 619.54 673.46 C 624.54 669.47 629.95 666.00 635.03 662.11 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 282.46 686.14 C 291.87 688.01 300.75 691.93 309.98 694.51 C 309.80 700.87 302.83 704.85 297.02 704.78 C 291.36 705.19 286.06 701.65 283.56 696.69 C 281.66 693.51 282.46 689.65 282.46 686.14 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 535.97 694.61 C 545.17 691.90 554.09 688.16 563.48 686.14 C 564.17 691.21 563.81 697.06 559.64 700.64 C 552.91 708.22 537.62 705.10 535.97 694.61 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 504.20 704.96 C 513.67 702.11 522.91 698.35 532.56 696.15 C 533.07 700.51 533.09 705.39 530.12 708.96 C 526.54 714.02 519.48 716.48 513.64 714.20 C 509.12 712.94 506.11 709.03 504.20 704.96 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 473.63 714.98 C 482.88 711.91 492.07 708.53 501.54 706.16 C 501.65 708.97 501.94 711.84 501.42 714.65 C 499.46 720.81 493.42 725.10 487.01 725.30 C 481.11 724.72 474.94 721.16 473.63 714.98 Z\"><\/path><path fill=\"#025332\" opacity=\"1.00\" d=\" M 376.17 715.45 C 385.77 715.43 395.37 715.40 404.97 715.47 C 405.02 721.55 401.12 727.54 395.16 729.25 C 386.42 732.96 375.02 725.12 376.17 715.45 Z\"><\/path><\/g><g id=\"#065533ff\"><path fill=\"#065533\" opacity=\"1.00\" d=\" M 425.53 147.59 C 429.28 145.15 436.45 145.71 437.43 151.00 C 437.89 154.44 434.93 156.89 432.93 159.27 C 434.85 161.37 436.91 163.33 439.11 165.14 C 440.46 162.73 441.38 160.11 441.78 157.38 C 443.43 157.42 445.08 157.46 446.74 157.52 C 446.17 161.34 444.47 164.81 443.08 168.37 C 444.27 169.34 445.54 170.25 446.61 171.38 C 446.87 173.08 444.97 173.85 444.09 175.00 C 442.43 173.95 440.78 172.89 439.12 171.87 C 434.30 173.91 428.22 175.66 423.54 172.38 C 420.73 170.69 421.20 167.08 421.48 164.29 C 422.19 162.11 424.17 160.62 425.61 158.91 C 423.54 155.60 421.71 150.39 425.53 147.59 M 428.13 150.37 C 428.24 152.29 428.55 154.19 429.06 156.05 C 431.64 155.17 433.28 152.97 432.27 150.21 C 430.88 150.25 429.50 150.30 428.13 150.37 M 428.20 161.95 C 426.54 163.79 426.19 166.16 426.35 168.55 C 429.10 170.62 432.40 170.28 435.40 168.93 C 433.42 166.21 431.01 163.81 428.20 161.95 Z\"><\/path><path fill=\"#065533\" opacity=\"1.00\" d=\" M 360.13 156.47 C 361.57 156.40 363.02 156.34 364.48 156.28 C 366.34 164.30 369.54 171.98 370.87 180.13 C 368.87 180.60 366.91 181.16 364.94 181.69 C 360.18 177.26 355.76 172.50 351.00 168.08 C 352.34 173.51 354.28 178.78 355.61 184.21 C 354.27 184.74 352.93 185.26 351.59 185.78 C 348.48 177.91 346.44 169.61 344.29 161.42 C 346.40 160.74 348.56 160.27 350.76 160.00 C 355.47 164.63 360.18 169.26 364.85 173.94 C 363.24 168.13 360.44 162.56 360.13 156.47 Z\"><\/path><path fill=\"#065533\" opacity=\"1.00\" d=\" M 473.41 175.58 C 470.31 168.85 473.10 159.29 480.33 156.48 C 484.93 154.57 490.01 156.15 494.37 157.96 C 496.39 158.59 495.08 161.01 495.26 162.51 C 491.94 162.71 489.25 160.13 485.94 160.26 C 478.04 159.23 474.02 172.50 481.16 176.02 C 482.79 176.77 484.54 177.22 486.26 177.74 C 487.33 174.88 488.10 171.93 488.82 168.97 C 490.31 169.47 492.66 169.02 493.29 170.88 C 492.70 174.43 491.62 177.88 491.09 181.44 C 484.83 182.19 477.05 181.47 473.41 175.58 Z\"><\/path><path fill=\"#065533\" opacity=\"1.00\" d=\" M 503.71 161.17 C 508.35 161.80 512.66 163.76 516.92 165.61 C 516.64 166.43 516.08 168.07 515.80 168.88 C 512.81 168.46 509.98 167.38 507.15 166.37 C 506.56 168.27 505.94 170.17 505.34 172.07 C 507.84 172.97 510.35 173.87 512.87 174.75 C 512.69 175.56 512.34 177.19 512.17 178.00 C 509.23 177.68 506.42 176.83 503.56 176.19 C 503.01 178.24 502.49 180.30 502.09 182.38 C 504.59 183.22 507.10 184.06 509.63 184.85 C 509.42 186.22 509.19 187.58 508.94 188.94 C 504.30 187.98 499.96 186.01 495.50 184.46 C 498.43 176.77 501.07 168.96 503.71 161.17 Z\"><\/path><path fill=\"#065533\" opacity=\"1.00\" d=\" M 302.23 179.89 C 304.03 179.17 306.60 176.04 308.26 178.60 C 313.18 184.78 318.30 190.81 322.92 197.22 C 321.23 197.97 318.66 200.11 317.19 197.90 C 313.99 193.88 310.88 189.78 307.55 185.86 C 309.16 191.50 310.32 197.28 311.43 203.03 C 310.67 204.89 307.96 206.44 306.22 204.86 C 302.32 201.59 298.83 197.85 294.75 194.79 C 296.44 199.93 299.02 204.72 300.79 209.83 C 299.43 210.58 298.07 211.32 296.72 212.06 C 293.19 204.24 290.15 196.20 287.42 188.08 C 289.41 187.43 291.97 185.08 293.91 187.06 C 297.88 190.72 302.01 194.22 305.93 197.95 C 304.74 191.92 303.06 185.98 302.23 179.89 Z\"><\/path><path fill=\"#065533\" opacity=\"1.00\" d=\" M 585.44 211.63 C 588.94 211.14 593.05 210.68 596.04 213.02 C 599.58 215.42 602.44 219.57 601.54 224.04 C 600.52 228.78 597.06 232.90 592.70 234.97 C 586.44 237.53 578.45 234.76 576.01 228.22 C 573.65 221.26 579.16 214.14 585.44 211.63 M 586.59 216.64 C 583.87 218.39 581.65 221.01 580.71 224.13 C 579.74 228.47 584.57 232.75 588.78 231.31 C 592.30 229.77 595.23 226.71 596.33 222.99 C 597.52 217.91 590.80 213.15 586.59 216.64 Z\"><\/path><path fill=\"#065533\" opacity=\"1.00\" d=\" M 609.78 264.20 C 616.52 259.65 622.72 254.18 629.78 250.19 C 633.08 253.23 635.29 257.35 637.77 261.08 C 637.03 261.58 635.54 262.57 634.79 263.07 C 632.80 260.90 631.01 258.57 629.13 256.31 C 627.72 257.37 626.30 258.42 624.89 259.47 C 626.10 262.14 628.20 264.40 628.82 267.33 C 627.90 267.79 627.00 268.24 626.10 268.71 C 624.42 266.56 622.76 264.40 621.13 262.22 C 619.37 263.42 617.63 264.64 615.93 265.91 C 617.46 268.36 619.14 270.72 620.84 273.07 C 619.84 273.97 618.84 274.87 617.87 275.79 C 614.84 272.18 611.81 268.49 609.78 264.20 Z\"><\/path><path fill=\"#065533\" opacity=\"1.00\" d=\" M 184.44 323.71 C 191.14 321.10 200.14 323.97 203.14 330.79 C 206.07 336.12 203.22 343.29 198.27 346.35 C 191.06 349.30 181.47 345.54 178.78 338.05 C 177.37 332.82 179.38 326.22 184.44 323.71 M 186.46 328.52 C 182.87 330.00 182.72 334.25 183.53 337.50 C 186.25 341.38 191.32 342.44 195.76 341.60 C 199.97 340.36 201.10 334.00 197.81 331.19 C 194.81 328.40 190.37 327.62 186.46 328.52 Z\"><\/path><path fill=\"#065533\" opacity=\"1.00\" d=\" M 184.97 438.31 C 188.14 435.58 190.95 432.43 194.34 429.94 C 194.76 431.67 195.19 433.41 195.63 435.15 C 192.76 437.93 189.54 440.36 186.94 443.42 C 189.96 443.61 192.93 443.08 195.91 442.70 C 197.23 443.80 196.58 445.86 196.92 447.39 C 188.60 448.51 180.33 450.60 171.92 450.64 C 171.75 445.87 169.10 440.54 172.20 436.19 C 174.23 434.10 177.92 432.54 180.59 434.38 C 182.29 435.39 183.48 437.03 184.97 438.31 M 175.50 439.46 C 175.34 441.55 175.30 443.65 175.37 445.76 C 177.87 445.50 180.32 444.93 182.73 444.24 C 182.25 442.75 181.84 441.24 181.15 439.84 C 179.45 438.84 177.36 439.47 175.50 439.46 Z\"><\/path><path fill=\"#065533\" opacity=\"1.00\" d=\" M 656.43 452.67 C 661.96 451.34 668.34 452.38 672.41 456.60 C 678.00 462.12 676.05 473.66 668.22 475.98 C 661.93 477.48 654.03 475.28 651.03 469.14 C 647.87 463.53 650.45 455.21 656.43 452.67 M 658.17 457.77 C 654.46 458.91 653.83 463.10 654.68 466.39 C 657.45 471.00 663.58 471.66 668.34 470.34 C 670.42 469.04 671.30 466.41 671.19 464.07 C 670.19 458.47 663.01 456.38 658.17 457.77 Z\"><\/path><path fill=\"#065533\" opacity=\"1.00\" d=\" M 199.85 493.64 C 202.94 492.18 206.06 490.65 209.46 490.06 C 210.05 491.97 211.35 493.79 211.25 495.84 C 207.83 501.20 203.46 505.90 200.04 511.27 C 205.19 509.07 210.24 506.66 215.35 504.37 C 216.05 505.80 216.68 507.27 217.23 508.77 C 209.52 512.12 202.01 516.01 194.04 518.71 C 193.41 516.29 191.01 513.41 193.14 511.11 C 196.59 506.34 200.31 501.79 203.75 497.02 C 198.33 499.22 193.25 502.30 187.58 503.85 C 187.09 502.54 186.59 501.23 186.10 499.93 C 190.48 497.40 195.31 495.84 199.85 493.64 Z\"><\/path><\/g><g id=\"#f2f6f4ff\"><path fill=\"#f2f6f4\" opacity=\"1.00\" d=\" M 428.13 150.37 C 429.50 150.30 430.88 150.25 432.27 150.21 C 433.28 152.97 431.64 155.17 429.06 156.05 C 428.55 154.19 428.24 152.29 428.13 150.37 Z\"><\/path><path fill=\"#f2f6f4\" opacity=\"1.00\" d=\" M 665.80 419.03 C 669.29 419.43 672.46 421.02 675.47 422.77 C 672.23 423.72 668.97 424.66 665.59 424.85 C 665.66 422.91 665.73 420.97 665.80 419.03 Z\"><\/path><\/g><g id=\"#075533ff\"><path fill=\"#075533\" opacity=\"1.00\" d=\" M 373.29 153.83 C 378.35 152.35 383.71 151.84 388.94 152.56 C 395.91 155.28 397.04 164.49 394.77 170.72 C 391.60 177.06 383.85 177.82 377.64 178.67 C 375.45 170.55 374.57 162.13 373.29 153.83 M 379.06 156.48 C 379.23 162.33 380.35 168.11 381.69 173.79 C 384.86 173.34 388.70 172.52 390.07 169.21 C 391.34 164.87 390.66 159.18 386.49 156.61 C 384.04 156.14 381.53 156.44 379.06 156.48 Z\"><\/path><path fill=\"#075533\" opacity=\"1.00\" d=\" M 512.22 190.08 C 516.74 183.07 521.40 176.10 526.33 169.37 C 528.37 169.39 530.02 170.79 531.78 171.65 C 531.03 177.30 529.99 182.91 529.44 188.58 C 534.21 185.15 537.51 180.16 541.94 176.33 C 543.59 177.22 545.27 178.08 546.96 178.92 C 544.84 186.48 542.35 193.93 540.26 201.50 C 539.53 203.93 536.75 201.81 535.25 201.47 C 536.37 195.50 538.40 189.70 540.49 184.00 C 536.38 188.55 532.18 193.02 527.78 197.28 C 526.08 197.47 524.80 195.81 523.32 195.18 C 524.23 190.63 524.74 186.01 524.70 181.38 C 520.99 183.99 519.36 188.46 516.59 191.92 C 515.11 191.35 513.66 190.72 512.22 190.08 Z\"><\/path><path fill=\"#075533\" opacity=\"1.00\" d=\" M 269.13 201.53 C 270.43 200.48 271.73 199.44 273.04 198.40 C 280.76 202.91 288.11 208.07 295.43 213.20 C 294.23 214.06 293.17 215.18 291.77 215.72 C 289.54 215.89 287.62 213.22 285.41 214.44 C 283.26 215.72 281.42 217.44 279.47 218.98 C 279.90 220.83 280.36 222.68 280.73 224.54 C 279.43 225.31 278.13 226.08 276.82 226.84 C 274.41 218.36 270.82 210.20 269.13 201.53 M 274.82 205.08 C 275.56 208.46 276.55 211.78 277.80 215.01 C 279.30 213.56 282.83 212.93 282.53 210.44 C 280.12 208.43 277.40 206.84 274.82 205.08 Z\"><\/path><path fill=\"#075533\" opacity=\"1.00\" d=\" M 202.93 276.55 C 211.55 278.32 220.31 279.40 228.92 281.26 C 228.33 282.76 227.64 284.22 226.90 285.66 C 224.94 285.55 222.98 285.46 221.03 285.40 C 219.61 287.92 218.17 290.42 216.87 293.00 C 217.84 294.59 219.49 295.94 219.75 297.87 C 219.27 299.07 218.59 300.18 217.98 301.33 C 212.12 295.71 207.06 289.33 201.59 283.34 C 199.06 281.33 202.04 278.63 202.93 276.55 M 206.32 282.24 C 208.90 284.81 211.27 287.58 214.00 290.00 C 215.08 288.09 216.10 286.15 216.99 284.14 C 213.47 283.28 209.90 282.71 206.32 282.24 Z\"><\/path><path fill=\"#075533\" opacity=\"1.00\" d=\" M 648.69 343.40 C 656.77 341.06 664.98 339.09 673.22 337.35 C 674.70 341.91 676.59 346.73 675.49 351.59 C 674.79 354.03 672.03 354.62 670.05 355.63 C 668.45 354.95 666.87 354.27 665.30 353.54 C 664.29 355.32 663.28 357.31 661.33 358.22 C 658.40 358.89 654.99 358.42 653.05 355.93 C 650.32 352.29 650.13 347.56 648.69 343.40 M 664.21 344.76 C 665.09 346.87 665.58 349.58 668.06 350.40 C 669.19 350.06 670.31 349.70 671.43 349.31 C 671.45 347.30 671.37 345.30 671.27 343.31 C 668.81 343.18 666.41 343.71 664.21 344.76 M 654.27 346.85 C 654.16 349.67 655.27 353.95 658.94 353.31 C 662.55 352.78 661.58 348.24 660.91 345.75 C 658.67 345.24 656.46 346.52 654.27 346.85 Z\"><\/path><path fill=\"#075533\" opacity=\"1.00\" d=\" M 172.44 359.23 C 173.83 359.25 175.22 359.28 176.62 359.31 C 176.43 361.45 176.25 363.60 176.14 365.75 C 182.87 367.37 190.03 367.20 196.52 369.69 C 196.21 371.02 195.90 372.36 195.60 373.70 C 188.59 373.23 181.77 371.14 174.72 371.08 C 174.52 372.95 174.33 374.82 174.09 376.69 C 172.83 376.70 171.57 376.72 170.31 376.75 C 170.16 370.82 171.70 365.07 172.44 359.23 Z\"><\/path><path fill=\"#075533\" opacity=\"1.00\" d=\" M 676.86 435.05 C 678.20 435.23 679.56 435.42 680.92 435.61 C 680.13 441.32 678.88 446.96 678.26 452.69 C 676.95 452.64 675.64 452.60 674.34 452.57 C 674.43 450.36 674.55 448.15 674.65 445.95 C 667.91 444.96 661.19 443.82 654.49 442.61 C 654.53 441.16 654.57 439.72 654.62 438.28 C 661.69 438.00 668.44 440.52 675.46 440.94 C 675.94 438.97 676.38 437.01 676.86 435.05 Z\"><\/path><path fill=\"#075533\" opacity=\"1.00\" d=\" M 645.97 476.97 C 654.07 479.10 661.79 482.52 669.76 485.10 C 668.55 489.78 667.36 495.14 663.41 498.31 C 660.87 498.80 657.76 499.14 655.75 497.18 C 653.73 495.51 653.31 492.76 652.39 490.45 C 648.38 491.61 644.33 492.63 640.27 493.57 C 641.04 491.61 641.04 488.93 643.12 487.83 C 646.71 486.71 650.44 486.16 654.08 485.23 C 651.05 483.77 647.92 482.53 644.82 481.26 C 645.21 479.83 645.59 478.40 645.97 476.97 M 657.16 491.66 C 657.92 493.61 660.11 493.82 661.89 493.38 C 663.49 492.14 663.76 490.17 663.94 488.30 C 661.83 487.51 659.70 486.79 657.58 486.10 C 657.29 487.89 655.97 489.92 657.16 491.66 Z\"><\/path><\/g><g id=\"#fbfcfcff\"><path fill=\"#fbfcfc\" opacity=\"1.00\" d=\" M 379.06 156.48 C 381.53 156.44 384.04 156.14 386.49 156.61 C 390.66 159.18 391.34 164.87 390.07 169.21 C 388.70 172.52 384.86 173.34 381.69 173.79 C 380.35 168.11 379.23 162.33 379.06 156.48 Z\"><\/path><path fill=\"#fbfcfc\" opacity=\"1.00\" d=\" M 665.31 367.27 C 669.94 365.36 676.99 368.28 676.30 373.98 C 676.10 378.25 671.34 379.76 667.84 380.41 C 664.08 380.97 659.00 378.30 659.43 374.00 C 658.82 370.44 662.20 367.92 665.31 367.27 Z\"><\/path><path fill=\"#fbfcfc\" opacity=\"1.00\" d=\" M 658.17 457.77 C 663.01 456.38 670.19 458.47 671.19 464.07 C 671.30 466.41 670.42 469.04 668.34 470.34 C 663.58 471.66 657.45 471.00 654.68 466.39 C 653.83 463.10 654.46 458.91 658.17 457.77 Z\"><\/path><\/g><g id=\"#f5f8f7ff\"><path fill=\"#f5f8f7\" opacity=\"1.00\" d=\" M 428.20 161.95 C 431.01 163.81 433.42 166.21 435.40 168.93 C 432.40 170.28 429.10 170.62 426.35 168.55 C 426.19 166.16 426.54 163.79 428.20 161.95 Z\"><\/path><path fill=\"#f5f8f7\" opacity=\"1.00\" d=\" M 664.21 344.76 C 666.41 343.71 668.81 343.18 671.27 343.31 C 671.37 345.30 671.45 347.30 671.43 349.31 C 670.31 349.70 669.19 350.06 668.06 350.40 C 665.58 349.58 665.09 346.87 664.21 344.76 Z\"><\/path><\/g><g id=\"#065432ff\"><path fill=\"#065432\" opacity=\"1.00\" d=\" M 326.62 167.87 C 329.34 166.57 332.70 165.78 335.48 167.39 C 339.58 169.09 341.72 173.31 343.05 177.29 C 344.80 182.37 342.45 188.30 337.94 191.10 C 334.81 193.43 330.63 192.94 326.99 192.53 C 320.92 189.15 318.05 181.32 319.98 174.73 C 320.97 171.54 323.57 169.11 326.62 167.87 M 327.48 172.37 C 323.21 174.62 323.90 180.47 325.95 184.04 C 327.41 187.20 331.33 189.78 334.71 187.83 C 338.80 186.12 339.60 180.91 337.52 177.32 C 336.09 173.51 331.51 169.46 327.48 172.37 Z\"><\/path><path fill=\"#065432\" opacity=\"1.00\" d=\" M 194.26 453.41 C 195.49 453.03 196.72 452.67 197.96 452.32 C 199.21 456.73 200.65 461.14 200.97 465.74 C 192.99 467.79 185.01 469.83 176.95 471.54 C 175.79 467.13 174.24 462.76 174.22 458.16 C 175.00 457.90 176.56 457.40 177.34 457.15 C 178.28 459.99 179.06 462.88 179.82 465.78 C 181.62 465.40 183.39 464.91 185.14 464.37 C 184.70 461.70 184.39 459.00 183.60 456.41 C 184.82 456.05 186.04 455.71 187.27 455.37 C 188.17 458.07 188.96 460.82 189.83 463.54 C 191.82 462.96 193.83 462.43 195.86 461.96 C 195.39 459.09 194.66 456.28 194.26 453.41 Z\"><\/path><\/g><g id=\"#fafcfbff\"><path fill=\"#fafcfb\" opacity=\"1.00\" d=\" M 327.48 172.37 C 331.51 169.46 336.09 173.51 337.52 177.32 C 339.60 180.91 338.80 186.12 334.71 187.83 C 331.33 189.78 327.41 187.20 325.95 184.04 C 323.90 180.47 323.21 174.62 327.48 172.37 Z\"><\/path><\/g><g id=\"#065532ff\"><path fill=\"#065532\" opacity=\"1.00\" d=\" M 550.49 192.18 C 550.58 189.60 553.00 187.81 555.01 186.55 C 559.43 185.44 563.27 188.03 566.72 190.41 C 566.57 191.36 566.41 192.30 566.27 193.25 C 565.74 193.41 564.67 193.73 564.14 193.89 C 562.08 192.65 560.16 190.44 557.58 190.63 C 555.84 191.46 555.86 193.88 556.67 195.37 C 558.18 198.48 561.37 201.24 560.50 205.03 C 559.45 208.13 556.39 210.70 553.02 210.46 C 548.71 210.62 545.23 207.63 542.27 204.88 C 543.30 203.77 544.49 201.15 546.29 202.75 C 548.62 204.72 551.34 206.31 554.52 205.49 C 556.03 200.28 549.50 197.31 550.49 192.18 Z\"><\/path><path fill=\"#065532\" opacity=\"1.00\" d=\" M 181.33 382.37 C 185.77 381.26 190.07 379.50 194.67 379.14 C 194.59 380.78 194.50 382.43 194.40 384.07 C 192.77 384.52 191.15 385.01 189.54 385.53 C 188.79 388.59 188.45 391.72 188.54 394.87 C 190.18 395.57 191.82 396.27 193.46 396.97 C 193.42 398.56 193.38 400.16 193.33 401.76 C 184.91 398.52 176.52 395.12 168.39 391.20 C 168.74 389.40 168.28 387.23 169.73 385.83 C 173.44 384.21 177.45 383.48 181.33 382.37 M 174.96 388.95 C 177.89 390.85 181.17 392.11 184.51 393.10 C 184.73 391.04 185.03 389.00 185.32 386.96 C 181.79 387.18 178.38 388.13 174.96 388.95 Z\"><\/path><path fill=\"#065532\" opacity=\"1.00\" d=\" M 168.33 405.69 C 175.57 405.47 182.86 405.89 190.05 404.82 C 191.19 404.74 192.31 404.84 193.44 405.10 C 193.41 407.19 193.41 409.29 193.42 411.39 C 187.66 414.92 182.04 418.71 176.03 421.81 C 181.94 421.64 187.85 421.16 193.78 421.24 C 193.75 422.70 193.73 424.17 193.73 425.65 C 185.43 425.94 177.15 426.70 168.83 426.68 C 168.68 424.72 168.56 422.75 168.41 420.79 C 173.09 416.82 179.14 414.76 183.49 410.42 C 178.43 410.18 173.38 410.65 168.32 410.60 C 168.32 408.96 168.32 407.32 168.33 405.69 Z\"><\/path><\/g><g id=\"#075634ff\"><path fill=\"#075634\" opacity=\"1.00\" d=\" M 569.80 194.92 C 570.30 194.73 571.31 194.34 571.81 194.15 C 576.53 197.68 581.43 200.97 585.91 204.82 C 584.95 205.81 584.01 206.81 583.07 207.80 C 581.38 206.56 579.66 205.37 577.93 204.21 C 573.61 209.67 569.86 215.58 565.21 220.78 C 564.12 219.98 563.04 219.19 561.96 218.41 C 564.69 211.92 570.35 207.18 573.74 201.02 C 572.25 199.84 570.77 198.67 569.30 197.48 C 569.46 196.63 569.63 195.77 569.80 194.92 Z\"><\/path><path fill=\"#075634\" opacity=\"1.00\" d=\" M 635.04 305.22 C 642.49 301.84 649.97 298.53 657.41 295.11 C 658.16 296.60 658.68 298.19 659.00 299.84 C 652.97 302.67 646.84 305.26 640.81 308.07 C 641.82 310.80 642.94 313.50 643.69 316.32 C 642.31 316.48 640.96 316.64 639.60 316.78 C 637.91 313.00 635.89 309.30 635.04 305.22 Z\"><\/path><path fill=\"#075634\" opacity=\"1.00\" d=\" M 663.33 362.28 C 668.62 360.70 675.13 361.89 678.49 366.57 C 682.41 371.79 681.76 381.19 675.04 383.82 C 668.14 387.73 657.39 385.17 655.24 376.90 C 652.73 370.79 656.77 363.31 663.33 362.28 M 665.31 367.27 C 662.20 367.92 658.82 370.44 659.43 374.00 C 659.00 378.30 664.08 380.97 667.84 380.41 C 671.34 379.76 676.10 378.25 676.30 373.98 C 676.99 368.28 669.94 365.36 665.31 367.27 Z\"><\/path><path fill=\"#075634\" opacity=\"1.00\" d=\" M 657.24 391.24 C 665.50 390.19 673.86 390.90 682.17 390.54 C 682.09 395.41 683.89 401.24 680.33 405.29 C 678.12 407.43 674.39 407.79 671.81 406.10 C 670.25 404.91 669.15 403.25 667.92 401.76 C 664.37 404.12 660.95 406.67 657.55 409.22 C 658.53 409.98 659.53 410.76 660.70 411.26 C 667.74 414.24 674.86 417.07 681.79 420.29 C 681.74 422.17 681.67 424.04 681.61 425.92 C 673.22 428.62 664.59 430.51 656.22 433.26 C 656.19 431.48 656.17 429.69 656.16 427.91 C 657.89 427.34 659.64 426.80 661.39 426.27 C 661.66 423.21 661.80 420.14 661.89 417.08 C 660.36 416.28 658.82 415.52 657.31 414.72 C 657.51 410.89 657.46 407.06 657.30 403.24 C 660.64 400.79 664.14 398.56 667.33 395.91 C 663.94 395.69 660.55 395.76 657.17 395.74 C 657.18 394.24 657.21 392.74 657.24 391.24 M 670.99 395.76 C 671.09 398.28 671.44 402.28 674.97 401.84 C 678.39 402.18 678.70 398.09 678.55 395.61 C 676.02 395.59 673.50 395.63 670.99 395.76 M 665.80 419.03 C 665.73 420.97 665.66 422.91 665.59 424.85 C 668.97 424.66 672.23 423.72 675.47 422.77 C 672.46 421.02 669.29 419.43 665.80 419.03 Z\"><\/path><\/g><g id=\"#f2f5f4ff\"><path fill=\"#f2f5f4\" opacity=\"1.00\" d=\" M 274.82 205.08 C 277.40 206.84 280.12 208.43 282.53 210.44 C 282.83 212.93 279.30 213.56 277.80 215.01 C 276.55 211.78 275.56 208.46 274.82 205.08 Z\"><\/path><\/g><g id=\"#075534ff\"><path fill=\"#075534\" opacity=\"1.00\" d=\" M 255.83 215.14 C 253.80 213.30 256.76 211.67 257.99 210.53 C 263.23 215.82 267.93 221.60 272.88 227.16 C 274.53 228.47 273.91 231.56 271.68 231.72 C 269.88 232.17 269.06 230.16 267.93 229.18 C 263.97 224.43 259.74 219.91 255.83 215.14 Z\"><\/path><path fill=\"#075534\" opacity=\"1.00\" d=\" M 246.49 222.65 C 255.62 220.00 265.04 230.37 261.97 239.23 C 260.39 243.83 256.49 246.99 252.93 250.06 C 248.50 246.52 244.79 242.21 240.64 238.37 C 238.62 236.52 236.68 234.58 235.13 232.31 C 238.56 228.74 241.72 224.48 246.49 222.65 M 241.43 231.97 C 245.16 236.07 249.23 239.82 253.21 243.66 C 255.37 242.01 257.88 239.94 257.65 236.92 C 258.10 232.78 254.64 229.52 251.30 227.73 C 247.35 226.19 243.58 228.78 241.43 231.97 Z\"><\/path><\/g><g id=\"#fafbfaff\"><\/g><g id=\"#fbfbfbff\"><\/g><g id=\"#fcfcfcff\"><path fill=\"#fcfcfc\" opacity=\"1.00\" d=\" M 586.59 216.64 C 590.80 213.15 597.52 217.91 596.33 222.99 C 595.23 226.71 592.30 229.77 588.78 231.31 C 584.57 232.75 579.74 228.47 580.71 224.13 C 581.65 221.01 583.87 218.39 586.59 216.64 Z\"><\/path><\/g><g id=\"#fafbfbff\"><path fill=\"#fafbfb\" opacity=\"1.00\" d=\" M 241.43 231.97 C 243.58 228.78 247.35 226.19 251.30 227.73 C 254.64 229.52 258.10 232.78 257.65 236.92 C 257.88 239.94 255.37 242.01 253.21 243.66 C 249.23 239.82 245.16 236.07 241.43 231.97 Z\"><\/path><path fill=\"#fafbfb\" opacity=\"1.00\" d=\" M 186.46 328.52 C 190.37 327.62 194.81 328.40 197.81 331.19 C 201.10 334.00 199.97 340.36 195.76 341.60 C 191.32 342.44 186.25 341.38 183.53 337.50 C 182.72 334.25 182.87 330.00 186.46 328.52 Z\"><\/path><\/g><g id=\"#065534ff\"><path fill=\"#065534\" opacity=\"1.00\" d=\" M 593.39 242.44 C 599.20 237.39 604.69 231.92 610.89 227.33 C 612.15 229.30 615.32 230.86 614.43 233.59 C 612.41 239.37 610.56 245.21 608.25 250.89 C 612.92 247.18 616.92 242.70 621.73 239.16 C 622.46 240.57 624.85 242.44 623.06 243.98 C 617.44 249.23 611.62 254.28 605.81 259.33 C 604.27 257.98 602.82 256.54 601.42 255.05 C 603.16 248.58 605.73 242.37 607.89 236.04 C 603.73 239.14 600.28 243.05 596.24 246.28 C 594.06 248.09 590.64 243.92 593.39 242.44 Z\"><\/path><path fill=\"#065534\" opacity=\"1.00\" d=\" M 174.34 349.28 C 182.57 350.31 190.63 352.56 198.76 354.24 C 198.62 355.89 198.47 357.55 198.32 359.21 C 190.35 357.38 182.34 355.65 174.30 354.16 C 174.30 352.53 174.33 350.90 174.34 349.28 Z\"><\/path><\/g><g id=\"#fcfdfdff\"><\/g><g id=\"#fdfdfdff\"><\/g><g id=\"#075535ff\"><path fill=\"#075535\" opacity=\"1.00\" d=\" M 212.63 261.04 C 219.28 263.40 224.10 269.02 230.46 271.99 C 231.93 270.00 233.11 267.73 235.03 266.12 C 236.33 266.43 238.20 267.09 237.78 268.81 C 236.01 272.39 233.41 275.46 231.10 278.70 C 224.11 274.05 217.00 269.53 210.40 264.33 C 211.15 263.23 211.89 262.13 212.63 261.04 Z\"><\/path><\/g><g id=\"#005430ff\"><path fill=\"#005430\" opacity=\"1.00\" d=\" M 366.73 263.66 C 368.75 263.06 371.78 261.18 373.30 263.60 C 379.34 271.13 385.92 278.21 391.74 285.92 C 387.11 292.22 381.47 297.98 378.51 305.33 C 375.84 311.18 371.79 316.37 369.84 322.55 C 383.25 322.66 396.66 322.56 410.07 322.61 C 411.96 322.70 413.77 322.16 415.53 321.52 C 415.94 319.61 416.34 317.71 416.68 315.79 C 418.89 317.27 421.15 319.25 423.95 319.29 C 426.58 318.71 428.87 317.19 431.23 315.96 C 431.59 318.27 430.44 322.94 434.18 322.58 C 447.66 322.48 461.15 322.87 474.62 322.38 C 471.71 314.47 468.66 306.60 465.04 299.00 C 462.97 294.45 459.55 290.77 456.52 286.87 C 456.38 284.89 456.61 282.91 456.63 280.93 C 464.85 277.13 469.14 268.84 475.15 262.53 C 508.82 273.01 538.60 295.28 558.73 324.19 C 580.32 355.05 590.86 393.51 587.86 431.04 C 585.78 459.71 576.01 487.84 559.62 511.48 C 557.93 514.60 553.99 513.83 551.02 514.29 C 496.68 514.58 442.34 514.09 388.00 514.37 C 361.00 514.37 334.00 514.35 307.00 514.38 C 301.64 514.57 296.36 513.44 291.01 513.67 C 289.69 513.90 288.60 513.18 287.98 512.06 C 270.64 486.83 260.20 456.70 259.24 426.04 C 258.40 421.05 258.50 415.97 259.28 410.98 C 259.87 390.58 264.91 370.43 272.99 351.74 C 290.77 311.35 325.96 279.80 366.73 263.66 M 373.05 277.90 C 348.04 286.65 325.91 302.68 308.75 322.76 C 323.19 322.38 337.65 322.75 352.09 322.55 C 356.83 311.31 362.72 300.59 369.28 290.31 C 372.32 285.50 376.14 281.23 378.93 276.26 C 376.94 276.72 374.99 277.28 373.05 277.90 M 472.34 277.72 C 479.64 292.59 487.58 307.15 493.89 322.48 C 508.55 322.66 523.22 322.71 537.88 322.46 C 533.06 315.93 526.84 310.62 520.96 305.09 C 506.71 293.01 490.25 283.21 472.34 277.72 M 298.41 338.50 C 296.29 339.64 295.21 341.95 293.98 343.91 C 284.24 360.80 277.81 379.61 275.22 398.93 C 274.73 402.18 274.23 405.54 274.79 408.81 C 275.53 410.91 278.04 411.11 279.94 411.26 C 284.95 411.31 289.98 411.28 295.00 411.20 C 308.41 409.93 321.83 411.80 335.26 411.62 C 335.04 392.04 337.33 372.49 341.90 353.45 C 343.21 348.40 344.87 343.43 345.99 338.33 C 332.66 338.19 319.33 338.45 306.00 338.22 C 303.47 338.25 300.91 338.07 298.41 338.50 M 363.21 338.33 C 360.02 346.65 357.90 355.34 355.86 364.00 C 352.92 379.14 350.75 394.53 351.39 409.99 C 353.21 416.52 352.04 423.30 352.32 429.97 C 352.35 439.56 355.35 448.85 355.47 458.44 C 356.96 469.58 359.18 480.64 362.00 491.52 C 362.89 494.15 363.24 497.74 366.21 498.89 C 369.69 500.36 373.45 498.46 377.05 498.56 C 380.91 498.04 384.08 501.13 387.93 500.82 C 394.58 500.76 401.23 500.95 407.88 500.73 C 415.16 499.14 422.84 499.12 430.13 500.70 C 439.75 501.00 449.38 500.71 459.00 500.82 C 463.07 500.68 467.31 501.38 471.20 499.82 C 475.25 498.56 480.85 500.98 483.50 496.53 C 485.95 491.62 486.64 486.03 487.88 480.73 C 491.81 460.78 494.37 440.34 492.83 420.00 C 493.31 392.32 487.63 364.90 479.99 338.42 C 464.67 338.33 449.33 338.14 434.02 338.49 C 423.36 340.78 412.69 337.81 402.00 338.29 C 389.07 338.31 376.14 338.25 363.21 338.33 M 500.13 338.35 C 499.79 345.16 502.56 351.52 503.56 358.16 C 507.08 374.17 508.27 390.54 509.38 406.86 C 509.16 409.80 512.36 411.46 514.94 411.29 C 530.63 411.30 546.32 411.14 562.00 411.32 C 565.24 411.23 569.22 412.44 571.78 409.82 C 574.46 406.93 572.57 402.95 572.17 399.60 C 569.38 378.80 562.36 358.56 551.36 340.67 C 550.51 339.06 548.94 338.00 547.07 338.28 C 531.42 338.37 515.78 338.28 500.13 338.35 M 274.67 428.56 C 273.83 432.33 274.85 436.16 275.47 439.89 C 278.21 459.58 285.13 478.65 295.32 495.72 C 296.42 497.77 298.42 499.61 300.92 499.41 C 316.46 499.41 332.00 499.44 347.54 499.39 C 347.48 497.64 347.61 495.89 347.23 494.19 C 344.41 483.59 342.20 472.82 340.74 461.95 C 339.68 453.93 337.91 446.03 337.04 438.00 C 336.24 434.16 336.68 430.18 335.65 426.39 C 319.11 425.99 302.55 426.51 286.01 426.17 C 282.24 425.87 277.05 424.68 274.67 428.56 M 507.46 458.94 C 506.03 472.21 502.98 485.22 500.17 498.24 C 502.02 498.95 503.95 499.56 505.97 499.44 C 519.33 499.39 532.70 499.43 546.06 499.42 C 548.51 499.63 550.66 497.93 551.85 495.91 C 561.87 479.13 568.73 460.45 571.67 441.11 C 572.31 436.60 572.98 432.04 572.50 427.49 C 567.38 426.52 562.17 426.85 557.00 426.79 C 541.19 426.72 525.38 426.60 509.57 426.39 C 509.39 437.27 508.60 448.11 507.46 458.94 Z\"><\/path><path fill=\"#005430\" opacity=\"1.00\" d=\" M 421.15 376.22 C 425.98 374.46 430.60 371.87 435.78 371.30 C 436.47 374.35 434.07 375.71 431.60 376.66 C 437.88 392.57 444.01 408.53 450.15 424.50 C 452.21 424.82 456.47 423.41 455.38 426.95 C 451.11 430.04 445.74 431.01 440.98 433.13 C 437.05 434.47 433.30 437.03 429.00 436.75 C 427.94 434.71 429.94 433.24 431.18 431.92 C 425.00 416.89 419.39 401.62 413.43 386.51 C 412.47 384.50 410.30 383.47 408.77 381.97 C 412.24 378.83 416.96 377.97 421.15 376.22 Z\"><\/path><\/g><g id=\"#f1f5f5ff\"><path fill=\"#f1f5f5\" opacity=\"1.00\" d=\" M 206.32 282.24 C 209.90 282.71 213.47 283.28 216.99 284.14 C 216.10 286.15 215.08 288.09 214.00 290.00 C 211.27 287.58 208.90 284.81 206.32 282.24 Z\"><\/path><\/g><g id=\"#055533ff\"><path fill=\"#055533\" opacity=\"1.00\" d=\" M 191.81 298.82 C 192.24 297.22 192.80 295.66 193.68 294.26 C 201.05 297.72 208.63 300.72 216.07 304.04 C 215.61 306.16 214.93 308.23 214.20 310.27 C 207.45 310.76 200.76 311.86 193.97 312.00 C 199.09 314.47 204.35 316.65 209.64 318.76 C 209.54 320.02 209.45 321.28 209.36 322.55 C 206.73 323.16 204.30 321.83 201.97 320.81 C 196.44 318.23 190.72 316.08 185.22 313.43 C 185.96 311.50 186.75 309.59 187.57 307.69 C 194.02 306.41 200.66 306.73 207.07 305.14 C 201.96 303.08 196.83 301.09 191.81 298.82 Z\"><\/path><\/g><g id=\"#085635ff\"><path fill=\"#085635\" opacity=\"1.00\" d=\" M 640.77 318.23 C 649.52 318.18 658.27 318.23 667.02 318.16 C 667.76 319.90 668.83 321.64 668.62 323.61 C 666.06 326.42 662.75 328.37 659.89 330.83 C 655.86 333.86 652.32 337.59 647.80 339.90 C 647.38 338.30 646.95 336.70 646.54 335.11 C 647.84 333.99 649.16 332.88 650.50 331.79 C 649.65 328.94 648.68 326.12 647.70 323.32 C 645.70 323.02 643.71 322.75 641.73 322.46 C 641.41 321.04 641.09 319.63 640.77 318.23 M 652.02 322.66 C 652.38 324.80 652.95 326.89 653.61 328.97 C 656.95 327.23 659.75 324.67 662.77 322.45 C 659.19 322.66 655.60 322.64 652.02 322.66 Z\"><\/path><\/g><g id=\"#f2f4f3ff\"><path fill=\"#f2f4f3\" opacity=\"1.00\" d=\" M 652.02 322.66 C 655.60 322.64 659.19 322.66 662.77 322.45 C 659.75 324.67 656.95 327.23 653.61 328.97 C 652.95 326.89 652.38 324.80 652.02 322.66 Z\"><\/path><\/g><g id=\"#feffffff\"><\/g><g id=\"#0a5835ff\"><path fill=\"#0a5835\" opacity=\"1.00\" d=\" M 411.56 351.43 C 416.28 349.63 420.88 347.38 425.85 346.34 C 426.13 347.50 426.38 348.66 426.62 349.84 C 418.06 353.13 409.58 356.61 400.92 359.64 C 400.51 358.93 399.68 357.53 399.27 356.83 C 402.94 354.17 407.40 353.08 411.56 351.43 Z\"><\/path><\/g><g id=\"#f6f9f8ff\"><path fill=\"#f6f9f8\" opacity=\"1.00\" d=\" M 654.27 346.85 C 656.46 346.52 658.67 345.24 660.91 345.75 C 661.58 348.24 662.55 352.78 658.94 353.31 C 655.27 353.95 654.16 349.67 654.27 346.85 Z\"><\/path><\/g><g id=\"#025430ff\"><path fill=\"#025430\" opacity=\"1.00\" d=\" M 408.27 359.68 C 412.65 358.01 416.92 355.82 421.61 355.10 C 423.72 360.14 425.37 365.38 427.71 370.33 C 423.53 372.75 418.91 374.24 414.40 375.89 C 412.20 370.54 409.84 365.25 408.27 359.68 Z\"><\/path><\/g><g id=\"#f3f6f6ff\"><path fill=\"#f3f6f6\" opacity=\"1.00\" d=\" M 174.96 388.95 C 178.38 388.13 181.79 387.18 185.32 386.96 C 185.03 389.00 184.73 391.04 184.51 393.10 C 181.17 392.11 177.89 390.85 174.96 388.95 Z\"><\/path><\/g><g id=\"#015430ff\"><path fill=\"#015430\" opacity=\"1.00\" d=\" M 406.27 406.30 C 407.71 402.21 408.75 397.80 412.14 394.78 C 415.01 398.58 415.82 403.26 415.73 407.91 C 418.87 411.43 421.63 415.47 421.95 420.35 C 419.81 420.39 417.62 419.95 415.53 420.46 C 405.38 432.95 404.51 450.49 408.25 465.56 C 422.16 465.59 436.08 465.58 449.99 465.57 C 453.53 465.61 457.14 465.27 460.62 466.17 C 460.62 467.65 460.63 469.14 460.63 470.64 C 437.03 470.81 413.42 470.85 389.82 470.62 C 389.73 468.28 390.70 466.13 391.32 463.93 C 389.41 451.37 389.32 438.07 394.00 426.07 C 396.50 418.61 401.21 412.21 406.27 406.30 Z\"><\/path><path fill=\"#015430\" opacity=\"1.00\" d=\" M 390.32 476.36 C 413.13 476.23 435.97 476.16 458.78 476.39 C 463.38 478.86 464.32 484.89 465.61 489.58 C 438.76 489.94 411.89 489.65 385.04 489.73 C 384.66 484.65 387.00 480.03 390.32 476.36 Z\"><\/path><\/g><g id=\"#f5f6f7ff\"><path fill=\"#f5f6f7\" opacity=\"1.00\" d=\" M 670.99 395.76 C 673.50 395.63 676.02 395.59 678.55 395.61 C 678.70 398.09 678.39 402.18 674.97 401.84 C 671.44 402.28 671.09 398.28 670.99 395.76 Z\"><\/path><\/g><g id=\"#f8f9faff\"><path fill=\"#f8f9fa\" opacity=\"1.00\" d=\" M 175.50 439.46 C 177.36 439.47 179.45 438.84 181.15 439.84 C 181.84 441.24 182.25 442.75 182.73 444.24 C 180.32 444.93 177.87 445.50 175.37 445.76 C 175.30 443.65 175.34 441.55 175.50 439.46 Z\"><\/path><\/g><g id=\"#05542fff\"><path fill=\"#05542f\" opacity=\"1.00\" d=\" M 415.38 457.01 C 415.13 455.11 417.35 454.11 418.97 454.42 C 431.32 454.46 443.69 454.29 456.05 454.50 C 458.68 454.43 457.52 457.85 457.75 459.48 C 455.19 459.90 452.62 460.35 450.02 460.28 C 440.01 460.19 430.00 460.35 419.99 460.21 C 418.11 460.06 414.96 459.62 415.38 457.01 Z\"><\/path><\/g><g id=\"#075633ff\"><path fill=\"#075633\" opacity=\"1.00\" d=\" M 178.22 477.41 C 179.55 476.79 180.96 476.33 182.40 476.04 C 182.96 477.88 183.49 479.74 183.95 481.63 C 190.95 480.50 197.36 477.22 204.21 475.48 C 204.74 477.02 205.27 478.57 205.77 480.14 C 199.18 482.14 192.73 484.58 186.13 486.55 C 186.63 488.73 187.19 490.90 187.67 493.10 C 186.34 493.33 185.01 493.55 183.67 493.77 C 181.89 488.30 180.26 482.78 178.22 477.41 Z\"><\/path><\/g><g id=\"#f4f9f8ff\"><path fill=\"#f4f9f8\" opacity=\"1.00\" d=\" M 657.16 491.66 C 655.97 489.92 657.29 487.89 657.58 486.10 C 659.70 486.79 661.83 487.51 663.94 488.30 C 663.76 490.17 663.49 492.14 661.89 493.38 C 660.11 493.82 657.92 493.61 657.16 491.66 Z\"><\/path><\/g><g id=\"#055532ff\"><path fill=\"#055532\" opacity=\"1.00\" d=\" M 636.37 501.07 C 639.34 501.88 642.02 503.44 644.92 504.47 C 650.89 504.82 656.89 504.34 662.88 504.57 C 662.08 506.18 661.28 507.78 660.49 509.40 C 656.67 509.38 652.86 509.29 649.06 509.52 C 651.19 512.50 654.05 514.97 655.85 518.19 C 656.05 520.01 654.87 521.54 654.16 523.12 C 650.86 519.28 647.86 515.20 644.58 511.35 C 642.18 508.35 638.43 507.10 635.08 505.51 C 635.48 504.02 635.90 502.53 636.37 501.07 Z\"><\/path><\/g><g id=\"#075635ff\"><path fill=\"#075635\" opacity=\"1.00\" d=\" M 198.89 526.05 C 205.91 522.17 212.94 518.29 220.03 514.54 C 221.56 515.11 221.92 517.03 222.90 518.22 C 216.46 522.46 209.49 525.86 202.73 529.55 C 200.17 531.08 199.27 527.93 198.89 526.05 Z\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ce4602 elementor-widget elementor-widget-heading\" data-id=\"1ce4602\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0646\u0628\u0630\u0629 \u0639\u0646 IDG<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a71415f elementor-widget elementor-widget-text-editor\" data-id=\"a71415f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div>\u064a\u064f\u0639\u062f \u0645\u062e\u062a\u0628\u0631 IDG \u0645\u062e\u062a\u0628\u0631\u064b\u0627 \u0633\u0639\u0648\u062f\u064a\u064b\u0627 \u0645\u062a\u062e\u0635\u0635\u064b\u0627 \u0641\u064a \u0641\u062d\u0635 \u0648\u062a\u0642\u064a\u064a\u0645 \u0648\u0627\u0639\u062a\u0645\u0627\u062f \u0627\u0644\u0623\u0644\u0645\u0627\u0633 \u0648\u0627\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629 \u0648\u0627\u0644\u0645\u0639\u0627\u062f\u0646 \u0648\u0627\u0644\u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0648\u0627\u0644\u0645\u0639\u0627\u062f\u0646 \u0627\u0644\u062b\u0645\u064a\u0646\u0629.\u00a0<\/div>\n<div>\u00a0\u0645\u062e\u062a\u0628\u0631 IDG \u0647\u0648 \u0645\u062e\u062a\u0628\u0631 \u0645\u0639\u062a\u0645\u062f \u0648\u062d\u0627\u0635\u0644 \u0639\u0644\u064a \u0634\u0647\u0627\u062f\u0629 \u0627\u0644\u0627\u064a\u0632\u0648 \u0648\u0641\u0642\u0627 \u0644\u0645\u062a\u0637\u0644\u0628\u0627\u062a \u0627\u0644\u0645\u0648\u0627\u0635\u0641\u0629 \u0627\u0644\u062f\u0648\u0644\u064a\u0629 ISO\/IEC17025-2017 \u0644\u0643\u0641\u0627\u0621\u0629 \u0645\u062e\u062a\u0628\u0631\u0627\u062a \u0627\u0644\u0641\u062d\u0635 \u0648\u0627\u0644\u0645\u0639\u0627\u064a\u0631\u0629 . \u0646\u062c\u0645\u0639 \u0628\u064a\u0646 \u0627\u0644\u062e\u0628\u0631\u0629 \u0627\u0644\u0639\u0644\u0645\u064a\u0629 \u0648\u0627\u0644\u062a\u0642\u0646\u064a\u0627\u062a \u0627\u0644\u062d\u062f\u064a\u062b\u0629 \u0644\u062a\u0642\u062f\u064a\u0645 \u062a\u0642\u0627\u0631\u064a\u0631 \u0648\u0634\u0647\u0627\u062f\u0627\u062a \u0645\u0639\u062a\u0645\u062f\u0629 \u0628\u0623\u0639\u0644\u0649 \u0645\u0639\u0627\u064a\u064a\u0631 \u0627\u0644\u062f\u0642\u0629 \u0648\u0627\u0644\u0645\u0648\u062b\u0648\u0642\u064a\u0629.<\/div>\n<div>\u00a0<\/div>\n<div>\u0646\u0624\u0645\u0646 \u0628\u0623\u0646 \u0627\u0644\u062b\u0642\u0629 \u0647\u064a \u0623\u0633\u0627\u0633 \u0647\u0630\u0627 \u0627\u0644\u0642\u0637\u0627\u0639\u060c \u0648\u0644\u0630\u0644\u0643 \u0646\u0644\u062a\u0632\u0645 \u0628\u0627\u0644\u062d\u064a\u0627\u062f \u0627\u0644\u062a\u0627\u0645 \u0648\u0627\u0644\u0634\u0641\u0627\u0641\u064a\u0629 \u0641\u064a \u062c\u0645\u064a\u0639 \u0639\u0645\u0644\u064a\u0627\u062a \u0627\u0644\u0641\u062d\u0635 \u0648\u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u0648\u0625\u0635\u062f\u0627\u0631 \u0627\u0644\u0634\u0647\u0627\u062f\u0627\u062a. \u0648\u0645\u0646 \u062e\u0644\u0627\u0644 \u0627\u0644\u062a\u0632\u0627\u0645\u0646\u0627 \u0628\u0627\u0644\u062c\u0648\u062f\u0629 \u0648\u0627\u0644\u0627\u062d\u062a\u0631\u0627\u0641\u064a\u0629\u060c \u0623\u0635\u0628\u062d\u062a \u0639\u0644\u0627\u0645\u0629 IDG \u0631\u0645\u0632\u064b\u0627 \u0644\u0644\u062a\u0645\u064a\u0632 \u0648\u0627\u0644\u0645\u0635\u062f\u0627\u0642\u064a\u0629 \u0641\u064a \u0633\u0648\u0642 \u0627\u0644\u0623\u0644\u0645\u0627\u0633 \u0648\u0627\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629 \u0648\u0627\u0644\u0645\u062c\u0648\u0647\u0631\u0627\u062a.<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-e0b2ca2 e-flex e-con-boxed e-con e-parent\" data-id=\"e0b2ca2\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5cf3456 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5cf3456\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u062c\u0648\u0627\u0647\u0631 \u0645\u0645\u064a\u0632\u0629<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70d1f57 eael-divider-center elementor-widget elementor-widget-eael-divider\" data-id=\"70d1f57\" data-element_type=\"widget\" data-widget_type=\"eael-divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"eael-divider-wrap divider-direction-horizontal\">\n\t\t\t\t\t\t\t<div class=\"divider-text-container\">\n\t\t\t\t\t<div class=\"divider-text-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"divider-border-wrap divider-border-left\">\n\t\t\t\t\t\t\t\t<span class=\"divider-border\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eael-divider-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eael-divider-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"false\" class=\"icon idg-icon-Pattern-2\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"divider-border-wrap divider-border-right\">\n\t\t\t\t\t\t\t\t<span class=\"divider-border\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f106ef elementor-hidden-desktop elementor-widget elementor-widget-image\" data-id=\"2f106ef\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"968\" src=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/2024\/08\/ring-2V4PH79.png\" class=\"attachment-full size-full wp-image-791\" alt=\"\" srcset=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/2024\/08\/ring-2V4PH79.png 1000w, https:\/\/idg-lab.com.sa\/wp-content\/uploads\/2024\/08\/ring-2V4PH79-300x290.png 300w, https:\/\/idg-lab.com.sa\/wp-content\/uploads\/2024\/08\/ring-2V4PH79-768x743.png 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-fd46482 e-flex e-con-boxed e-con e-parent\" data-id=\"fd46482\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-719aa44 e-con-full e-flex e-con e-child\" data-id=\"719aa44\" data-element_type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-c7d9874 e-con-full e-flex e-con e-child\" data-id=\"c7d9874\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-705fd58 elementor-widget elementor-widget-heading\" data-id=\"705fd58\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color:#EEAE53\">1. <\/span>  \u0627\u0644\u064a\u0627\u0642\u0648\u062a<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08fecc8 elementor-widget elementor-widget-text-editor\" data-id=\"08fecc8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0627\u0644\u064a\u0627\u0642\u0648\u062a \u0647\u0648 \u0623\u062d\u062f \u0623\u0643\u062b\u0631 \u0627\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629 \u0642\u064a\u0645\u0629\u064b \u0648\u062a\u0645\u064a\u0632\u064b\u0627 \u0641\u064a \u0627\u0644\u0639\u0627\u0644\u0645\u060c \u064a\u064f\u0639\u0631\u0641 \u0628\u0623\u0644\u0648\u0627\u0646\u0647 \u0627\u0644\u0632\u0627\u0647\u064a\u0629 \u0648\u0627\u0644\u0645\u062a\u0646\u0648\u0639\u0629 \u0648\u0635\u0644\u0627\u0628\u062a\u0647 \u0627\u0644\u0645\u0645\u062a\u0627\u0632\u0629. \u064a\u064f\u0639\u062f \u062c\u0632\u0621\u064b\u0627 \u0645\u0646 \u0639\u0627\u0626\u0644\u0629 \u0627\u0644\u0643\u0648\u0631\u0627\u0646\u062f\u0648\u0645\u060c \u0627\u0644\u062a\u064a \u062a\u0634\u0645\u0644 \u0623\u064a\u0636\u064b\u0627 \u0627\u0644\u064a\u0627\u0642\u0648\u062a \u0627\u0644\u0623\u0632\u0631\u0642.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-34adfcd e-con-full e-flex e-con e-child\" data-id=\"34adfcd\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17f2717 elementor-widget elementor-widget-heading\" data-id=\"17f2717\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color:#EEAE53\">2. <\/span>  \u0627\u0644\u0632\u0645\u0631\u062f<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f85466e elementor-widget elementor-widget-text-editor\" data-id=\"f85466e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0627\u0644\u0632\u0645\u0631\u062f \u0647\u0648 \u0623\u062d\u062f \u0623\u0646\u062f\u0631 \u0648\u0623\u062b\u0645\u0646 \u0627\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629 \u0641\u064a \u0627\u0644\u0639\u0627\u0644\u0645\u060c \u064a\u064f\u0639\u0631\u0641 \u0628\u0644\u0648\u0646\u0647 \u0627\u0644\u0623\u062e\u0636\u0631 \u0627\u0644\u063a\u0646\u064a \u0648\u0627\u0644\u0644\u0627\u0645\u0639. \u064a\u0646\u062a\u0645\u064a \u0625\u0644\u0649 \u0639\u0627\u0626\u0644\u0629 \u0627\u0644\u0628\u064a\u0631\u064a\u0644\u060c \u0627\u0644\u062a\u064a \u062a\u0634\u0645\u0644 \u0623\u064a\u0636\u064b\u0627 \u0627\u0644\u0623\u0643\u0648\u0627\u0645\u0627\u0631\u064a\u0646 \u0648\u0627\u0644\u0645\u0648\u0631\u063a\u0627\u0646\u064a\u062a.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-430171a e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"430171a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb0ee4f elementor-widget elementor-widget-image\" data-id=\"eb0ee4f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"968\" src=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/2024\/08\/ring-2V4PH79.png\" class=\"attachment-full size-full wp-image-791\" alt=\"\" srcset=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/2024\/08\/ring-2V4PH79.png 1000w, https:\/\/idg-lab.com.sa\/wp-content\/uploads\/2024\/08\/ring-2V4PH79-300x290.png 300w, https:\/\/idg-lab.com.sa\/wp-content\/uploads\/2024\/08\/ring-2V4PH79-768x743.png 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-8501297 e-con-full e-flex e-con e-child\" data-id=\"8501297\" data-element_type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-135bc20 e-con-full e-flex e-con e-child\" data-id=\"135bc20\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-429bfc0 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"429bfc0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color:#EEAE53\">3. <\/span>  \u0627\u0644\u0632\u0641\u064a\u0631<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2ea956 elementor-widget elementor-widget-text-editor\" data-id=\"a2ea956\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0627\u0644\u0632\u0641\u064a\u0631\u060c \u0627\u0644\u0645\u0639\u0631\u0648\u0641 \u0623\u064a\u0636\u064b\u0627 \u0628\u0627\u0633\u0645 \u0627\u0644\u064a\u0627\u0642\u0648\u062a \u0627\u0644\u0623\u0632\u0631\u0642\u060c \u0647\u0648 \u0623\u062d\u062f \u0623\u0628\u0631\u0632 \u0627\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629 \u0641\u064a \u0627\u0644\u0639\u0627\u0644\u0645\u060c \u0648\u064a\u064f\u0639\u0631\u0641 \u0628\u0644\u0648\u0646\u0647 \u0627\u0644\u0623\u0632\u0631\u0642 \u0627\u0644\u063a\u0646\u064a. \u064a\u0646\u062a\u0645\u064a \u0625\u0644\u0649 \u0639\u0627\u0626\u0644\u0629 \u0627\u0644\u0643\u0648\u0631\u0627\u0646\u062f\u0648\u0645\u060c \u0648\u0647\u064a \u0646\u0641\u0633 \u0627\u0644\u0639\u0627\u0626\u0644\u0629 \u0627\u0644\u062a\u064a \u062a\u0636\u0645 \u0627\u0644\u064a\u0627\u0642\u0648\u062a \u0627\u0644\u0623\u062d\u0645\u0631.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-03a1cc0 e-con-full e-flex e-con e-child\" data-id=\"03a1cc0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0091603 elementor-widget elementor-widget-heading\" data-id=\"0091603\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color:#EEAE53\">4. <\/span>   \u0627\u0644\u0623\u0644\u0645\u0627\u0633<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a80d42 elementor-widget elementor-widget-text-editor\" data-id=\"0a80d42\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0627\u0644\u0623\u0644\u0645\u0627\u0633 \u0647\u0648 \u0645\u0627\u062f\u0629 \u0643\u0631\u0628\u0648\u0646\u064a\u0629 \u062a\u062a\u0628\u0644\u0648\u0631 \u0641\u064a \u0646\u0638\u0627\u0645 \u0645\u0643\u0639\u0628\u060c \u0648\u064a\u064f\u0639\u062f \u0623\u0635\u0644\u0628 \u0645\u0627\u062f\u0629 \u0637\u0628\u064a\u0639\u064a\u0629 \u0645\u0639\u0631\u0648\u0641\u0629 \u062d\u062a\u0649 \u0627\u0644\u0622\u0646. \u064a\u064f\u0642\u062f\u0651\u064e\u0631 \u0644\u062c\u0645\u0627\u0644\u0647 \u0648\u0646\u062f\u0631\u062a\u0647 \u0648\u062e\u0635\u0627\u0626\u0635\u0647 \u0627\u0644\u0641\u0631\u064a\u062f\u0629\u060c \u0645\u0645\u0627 \u064a\u062c\u0639\u0644\u0647 \u0623\u0634\u0647\u0631 \u0627\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629 \u0648\u0623\u0643\u062b\u0631\u0647\u0627 \u0642\u064a\u0645\u0629\u064b.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-19e1f35 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"19e1f35\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a12e3d3 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a12e3d3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Featured Gems<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0989489 elementor-widget elementor-widget-eael-divider\" data-id=\"0989489\" data-element_type=\"widget\" data-widget_type=\"eael-divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"eael-divider-wrap divider-direction-horizontal\">\n\t\t\t\t\t\t\t<div class=\"eael-divider horizontal solid\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-a8df394 e-grid e-con-full e-con e-child\" data-id=\"a8df394\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a887366 featured-gems elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"a887366\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"73\" height=\"70\" src=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/2024\/08\/Featured-Gems-PERIDOT-14611-73x70-1.png\" class=\"attachment-full size-full wp-image-481\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Peridot<\/h3><p class=\"elementor-image-box-description\">Found in lava, meteorites, and deep in the earth\u2019s mantle, yellow-green peridot is the extreme gem.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9052ca3 featured-gems elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"9052ca3\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/elementor\/thumbs\/fancy-color-diamond-qswho5nrjyfnn8j5lie9dxyhxj7uidtv6cuea7dngc.png\" title=\"fancy-color-diamond\" alt=\"fancy-color-diamond\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Fancy Color Diamond<\/h3><p class=\"elementor-image-box-description\">Dazzling brilliance. Captivating color. These are the planet\u2019s most valued gems.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87f5891 featured-gems elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"87f5891\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/elementor\/thumbs\/diamond-qswhqtjax22wjgnw1nu7g9riiu3abiehjjdx8ffhto.png\" title=\"diamond\" alt=\"diamond\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Diamond<\/h3><p class=\"elementor-image-box-description\">Diamonds are among nature\u2019s most precious and beautiful creations.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0810b9 featured-gems elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"f0810b9\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/elementor\/thumbs\/Featured-Gems-CITRINE-151544-73x70-1-qswhtl671hvaq4n5vuwnskmdhog6zfe198je3rbri4.png\" title=\"Featured-Gems-CITRINE-151544-73\u00d770\" alt=\"Featured-Gems-CITRINE-151544-73x70\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Emerald<\/h3><p class=\"elementor-image-box-description\">Emerald is the bluish green to green variety of beryl, a mineral species that includes aquamarine.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-e7d396f e-con-full elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"e7d396f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c00cad elementor-widget-divider--separator-type-pattern elementor-widget-divider--no-spacing elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4c00cad\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;xMidYMid meet&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 126 26&#039; fill=&#039;black&#039; stroke=&#039;none&#039;%3E%3Cpath d=&#039;M3,10.2c2.6,0,2.6,2,2.6,3.2S4.4,16.5,3,16.5s-3-1.4-3-3.2S0.4,10.2,3,10.2z M18.8,10.2c1.7,0,3.2,1.4,3.2,3.2s-1.4,3.2-3.2,3.2c-1.7,0-3.2-1.4-3.2-3.2S17,10.2,18.8,10.2z M34.6,10.2c1.5,0,2.6,1.4,2.6,3.2s-0.5,3.2-1.9,3.2c-1.5,0-3.4-1.4-3.4-3.2S33.1,10.2,34.6,10.2z M50.5,10.2c1.7,0,3.2,1.4,3.2,3.2s-1.4,3.2-3.2,3.2c-1.7,0-3.3-0.9-3.3-2.6S48.7,10.2,50.5,10.2z M66.2,10.2c1.5,0,3.4,1.4,3.4,3.2s-1.9,3.2-3.4,3.2c-1.5,0-2.6-0.4-2.6-2.1S64.8,10.2,66.2,10.2z M82.2,10.2c1.7,0.8,2.6,1.4,2.6,3.2s-0.1,3.2-1.6,3.2c-1.5,0-3.7-1.4-3.7-3.2S80.5,9.4,82.2,10.2zM98.6,10.2c1.5,0,2.6,0.4,2.6,2.1s-1.2,4.2-2.6,4.2c-1.5,0-3.7-0.4-3.7-2.1S97.1,10.2,98.6,10.2z M113.4,10.2c1.2,0,2.2,0.9,2.2,3.2s-0.1,3.2-1.3,3.2s-3.1-1.4-3.1-3.2S112.2,10.2,113.4,10.2z&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-ffd389d e-flex e-con-boxed e-con e-parent\" data-id=\"ffd389d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b390bfb elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b390bfb\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0627\u0644\u0623\u0628\u062d\u0627\u062b \u0648\u0627\u0644\u0623\u062e\u0628\u0627\u0631<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b47861f eael-divider-center elementor-widget elementor-widget-eael-divider\" data-id=\"b47861f\" data-element_type=\"widget\" data-widget_type=\"eael-divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"eael-divider-wrap divider-direction-horizontal\">\n\t\t\t\t\t\t\t<div class=\"divider-text-container\">\n\t\t\t\t\t<div class=\"divider-text-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"divider-border-wrap divider-border-left\">\n\t\t\t\t\t\t\t\t<span class=\"divider-border\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eael-divider-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eael-divider-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"false\" class=\"icon idg-icon-Pattern-2\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"divider-border-wrap divider-border-right\">\n\t\t\t\t\t\t\t\t<span class=\"divider-border\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fda5c84 news elementor-widget elementor-widget-eael-post-carousel\" data-id=\"fda5c84\" data-element_type=\"widget\" data-settings=\"{&quot;items&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;items_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;items_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]}}\" data-widget_type=\"eael-post-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"swiper-container-wrap eael-post-grid-container eael-post-carousel-wrap eael-post-carousel-style-one swiper-container-wrap-dots-outside\" id=\"eael-post-grid-fda5c84\">\n            <div class=\"swiper swiper-8 eael-post-carousel eael-post-grid swiper-container-fda5c84 eael-post-appender-fda5c84 show-read-more-button\" data-pagination=\".swiper-pagination-fda5c84\" data-arrow-next=\".swiper-button-next-fda5c84\" data-arrow-prev=\".swiper-button-prev-fda5c84\" data-items-mobile=\"1\" data-items-tablet=\"2\" data-items=\"3\" data-effect=\"slide\" data-speed=\"400\" data-autoplay=\"0\" data-loop=\"1\" data-arrows=\"1\" data-dots=\"1\">\n                <div class=\"swiper-wrapper\">\n\t\t\t\t\t<div class=\"swiper-slide\"><article class=\"eael-grid-post eael-post-grid-column\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media eael-entry-medianone\"><div class=\"eael-entry-thumbnail \">\n                    <img decoding=\"async\" src=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/2024\/08\/SU24-GNI-Fig1-325154-636px.jpg\" alt=\"\">\n                    <a href=\"https:\/\/idg-lab.com.sa\/ar\/the-latest-in-field-gemology-from-wim-vertriest-3\/\"><\/a>\n                <\/div><\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><a class=\"eael-grid-post-link\" href=\"https:\/\/idg-lab.com.sa\/ar\/the-latest-in-field-gemology-from-wim-vertriest-3\/\" title=\"\u0623\u062d\u062f\u062b \u0645\u0627 \u062a\u0648\u0635\u0644 \u0625\u0644\u064a\u0647 \u0639\u0644\u0645 \u0627\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629 \u0645\u0646 \u0648\u064a\u0645 \u0641\u064a\u0631\u062a\u0631\u064a\u0633\u062a\"><h2 class=\"eael-entry-title\">\u0623\u062d\u062f\u062b \u0645\u0627 \u062a\u0648\u0635\u0644 \u0625\u0644\u064a\u0647 \u0639\u0644\u0645 \u0627\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629 \u0645\u0646 \u0648\u064a\u0645 \u0641\u064a\u0631\u062a\u0631\u064a\u0633\u062a<\/a><\/h2><div class=\"eael-entry-meta\"><\/div><\/header><\/div><div class=\"eael-entry-content\">\n\t\t\t\t<div class=\"eael-grid-post-excerpt\"><p>\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0623\u062d\u062f\u062b \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u062d\u0648\u0644 \u064a\u0627\u0642\u0648\u062a \u0645\u062f\u063a\u0634\u0642\u0631 \u0648\u062d\u062c\u0631 \u0627\u0644\u0639\u0642\u064a\u0642 \u0627\u0644\u062f\u064a\u0645\u0627\u0646\u062a\u0648\u064a\u062f \u0645\u0646 \u0648\u064a\u0645 \u0641\u064a\u0631\u062a\u0631\u064a\u0633\u062a\u060c \u0645\u062f\u064a\u0631 \u0642\u0633\u0645 \u0639\u0644\u0645 \u0627\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629 \u0627\u0644\u0645\u064a\u062f\u0627\u0646\u064a \u0641\u064a \u0627\u0644\u0645\u0639\u0647\u062f \u0627\u0644\u0623\u0645\u0631\u064a\u0643\u064a \u0644\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629.<\/p><div class=\"eael-post-elements-readmore-wrap\"><a href=\"https:\/\/idg-lab.com.sa\/ar\/the-latest-in-field-gemology-from-wim-vertriest-3\/\" class=\"eael-post-elements-readmore-btn\">\u0627\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f<\/a><\/div><\/div>\n\t\t\t<\/div><\/div><\/div><\/article><\/div><div class=\"swiper-slide\"><article class=\"eael-grid-post eael-post-grid-column\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media eael-entry-medianone\"><div class=\"eael-entry-thumbnail \">\n                    <img decoding=\"async\" src=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/2024\/08\/SU24-MW-Fig12-324898-636px.jpg\" alt=\"\">\n                    <a href=\"https:\/\/idg-lab.com.sa\/ar\/the-latest-in-field-gemology-from-wim-vertriest-2\/\"><\/a>\n                <\/div><\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><a class=\"eael-grid-post-link\" href=\"https:\/\/idg-lab.com.sa\/ar\/the-latest-in-field-gemology-from-wim-vertriest-2\/\" title=\"\u0623\u062d\u062f\u062b \u0645\u0627 \u062a\u0648\u0635\u0644 \u0625\u0644\u064a\u0647 \u0639\u0644\u0645 \u0627\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629 \u0645\u0646 \u0648\u064a\u0645 \u0641\u064a\u0631\u062a\u0631\u064a\u0633\u062a\"><h2 class=\"eael-entry-title\">\u0623\u062d\u062f\u062b \u0645\u0627 \u062a\u0648\u0635\u0644 \u0625\u0644\u064a\u0647 \u0639\u0644\u0645 \u0627\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629 \u0645\u0646 \u0648\u064a\u0645 \u0641\u064a\u0631\u062a\u0631\u064a\u0633\u062a<\/a><\/h2><div class=\"eael-entry-meta\"><\/div><\/header><\/div><div class=\"eael-entry-content\">\n\t\t\t\t<div class=\"eael-grid-post-excerpt\"><p>\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0623\u062d\u062f\u062b \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u062d\u0648\u0644 \u064a\u0627\u0642\u0648\u062a \u0645\u062f\u063a\u0634\u0642\u0631 \u0648\u062d\u062c\u0631 \u0627\u0644\u0639\u0642\u064a\u0642 \u0627\u0644\u062f\u064a\u0645\u0627\u0646\u062a\u0648\u064a\u062f \u0645\u0646 \u0648\u064a\u0645 \u0641\u064a\u0631\u062a\u0631\u064a\u0633\u062a\u060c \u0645\u062f\u064a\u0631 \u0642\u0633\u0645 \u0639\u0644\u0645 \u0627\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629 \u0627\u0644\u0645\u064a\u062f\u0627\u0646\u064a \u0641\u064a \u0627\u0644\u0645\u0639\u0647\u062f \u0627\u0644\u0623\u0645\u0631\u064a\u0643\u064a \u0644\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629.<\/p><div class=\"eael-post-elements-readmore-wrap\"><a href=\"https:\/\/idg-lab.com.sa\/ar\/the-latest-in-field-gemology-from-wim-vertriest-2\/\" class=\"eael-post-elements-readmore-btn\">\u0627\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f<\/a><\/div><\/div>\n\t\t\t<\/div><\/div><\/div><\/article><\/div><div class=\"swiper-slide\"><article class=\"eael-grid-post eael-post-grid-column\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media eael-entry-medianone\"><div class=\"eael-entry-thumbnail \">\n                    <img decoding=\"async\" src=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/2024\/08\/1-hero-636x358-1.jpg\" alt=\"\">\n                    <a href=\"https:\/\/idg-lab.com.sa\/ar\/the-latest-in-field-gemology-from-wim-vertriest\/\"><\/a>\n                <\/div><\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><a class=\"eael-grid-post-link\" href=\"https:\/\/idg-lab.com.sa\/ar\/the-latest-in-field-gemology-from-wim-vertriest\/\" title=\"\u0623\u062d\u062f\u062b \u0645\u0627 \u062a\u0648\u0635\u0644 \u0625\u0644\u064a\u0647 \u0639\u0644\u0645 \u0627\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629 \u0645\u0646 \u0648\u064a\u0645 \u0641\u064a\u0631\u062a\u0631\u064a\u0633\u062a\"><h2 class=\"eael-entry-title\">\u0623\u062d\u062f\u062b \u0645\u0627 \u062a\u0648\u0635\u0644 \u0625\u0644\u064a\u0647 \u0639\u0644\u0645 \u0627\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629 \u0645\u0646 \u0648\u064a\u0645 \u0641\u064a\u0631\u062a\u0631\u064a\u0633\u062a<\/a><\/h2><div class=\"eael-entry-meta\"><\/div><\/header><\/div><div class=\"eael-entry-content\">\n\t\t\t\t<div class=\"eael-grid-post-excerpt\"><p>\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0623\u062d\u062f\u062b \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u062d\u0648\u0644 \u064a\u0627\u0642\u0648\u062a \u0645\u062f\u063a\u0634\u0642\u0631 \u0648\u062d\u062c\u0631 \u0627\u0644\u0639\u0642\u064a\u0642 \u0627\u0644\u062f\u064a\u0645\u0627\u0646\u062a\u0648\u064a\u062f \u0645\u0646 \u0648\u064a\u0645 \u0641\u064a\u0631\u062a\u0631\u064a\u0633\u062a\u060c \u0645\u062f\u064a\u0631 \u0642\u0633\u0645 \u0639\u0644\u0645 \u0627\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629 \u0627\u0644\u0645\u064a\u062f\u0627\u0646\u064a \u0641\u064a \u0627\u0644\u0645\u0639\u0647\u062f \u0627\u0644\u0623\u0645\u0631\u064a\u0643\u064a \u0644\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629.<\/p><div class=\"eael-post-elements-readmore-wrap\"><a href=\"https:\/\/idg-lab.com.sa\/ar\/the-latest-in-field-gemology-from-wim-vertriest\/\" class=\"eael-post-elements-readmore-btn\">\u0627\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f<\/a><\/div><\/div>\n\t\t\t<\/div><\/div><\/div><\/article><\/div>                <\/div>\n            <\/div>\n            <div class=\"clearfix\"><\/div>\n\t\t\t            <!-- Add Pagination -->\n            <div class=\"swiper-pagination swiper-pagination-fda5c84\"><\/div>\n\t\t\t\t\t            <!-- Add Arrows -->\n            <div class=\"swiper-button-next swiper-button-next-fda5c84\">\n                <i class=\"fa fa-angle-right\"><\/i>\n            <\/div>\n            <div class=\"swiper-button-prev swiper-button-prev-fda5c84\">\n                <i class=\"fa fa-angle-left\"><\/i>\n            <\/div>\n\t\t\t        <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b92e8bf elementor-widget elementor-widget-menu-anchor\" data-id=\"b92e8bf\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"check-report\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-dc68756 e-flex e-con-boxed e-con e-parent\" data-id=\"dc68756\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-adb623a elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"adb623a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0627\u0644\u062a\u062d\u0642\u0642 \u0645\u0646 \u0627\u0644\u062a\u0642\u0631\u064a\u0631<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a75ecbe elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a75ecbe\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u062a\u0648\u0641\u0631 \u0644\u0643 \u062e\u062f\u0645\u062a\u0646\u0627 \u0644\u0644\u062a\u062d\u0642\u0642 \u0645\u0646 \u0627\u0644\u062a\u0642\u0627\u0631\u064a\u0631 \u0625\u0645\u0643\u0627\u0646\u064a\u0629 \u0627\u0644\u062a\u062d\u0642\u0642 \u0645\u0646 \u0635\u062d\u0629 \u062a\u0642\u0631\u064a\u0631\u0643 \u0628\u0643\u0644 \u0633\u0647\u0648\u0644\u0629. \u0645\u0627 \u0639\u0644\u064a\u0643 \u0633\u0648\u0649 \u0625\u062f\u062e\u0627\u0644 \u0631\u0642\u0645 \u0627\u0644\u062a\u0639\u0631\u064a\u0641 \u0627\u0644\u0641\u0631\u064a\u062f \u0641\u064a \u0627\u0644\u062d\u0642\u0644 \u0623\u062f\u0646\u0627\u0647. \u0633\u062a\u062a\u0645\u0643\u0646 \u0645\u0646 \u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0627\u0644\u062a\u0642\u0631\u064a\u0631 \u0639\u0628\u0631 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a\u060c \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0635\u0648\u0631\u0629 \u0639\u0627\u0644\u064a\u0629 \u0627\u0644\u062c\u0648\u062f\u0629 \u0644\u0642\u0637\u0639\u0629 \u0627\u0644\u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0627\u0644\u062e\u0627\u0635\u0629 \u0628\u0643.\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42548e6 elementor-widget__width-initial report-form elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"42548e6\" data-element_type=\"widget\" data-settings=\"{&quot;button_width&quot;:&quot;30&quot;,&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"25\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"42548e6\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-reportno elementor-col-70 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-reportno\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\t\u0627\u0644\u0631\u0642\u0645 \u0627\u0644\u0641\u0631\u064a\u062f\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[reportno]\" id=\"form-field-reportno\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"\u0627\u0644\u0631\u0642\u0645 \u0627\u0644\u0641\u0631\u064a\u062f\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-30 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-md\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\"> \u062a\u062d\u0642\u0642<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ab6235 elementor-widget elementor-widget-menu-anchor\" data-id=\"1ab6235\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"why-us\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-0a200f2 e-flex e-con-boxed e-con e-parent\" data-id=\"0a200f2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31e4d20 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"31e4d20\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0644\u0645\u0627\u0630\u0627 \u0646\u062d\u0646 \u061f<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-541068d eael-divider-center elementor-widget elementor-widget-eael-divider\" data-id=\"541068d\" data-element_type=\"widget\" data-widget_type=\"eael-divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"eael-divider-wrap divider-direction-horizontal\">\n\t\t\t\t\t\t\t<div class=\"divider-text-container\">\n\t\t\t\t\t<div class=\"divider-text-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"divider-border-wrap divider-border-left\">\n\t\t\t\t\t\t\t\t<span class=\"divider-border\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eael-divider-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eael-divider-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"false\" class=\"icon idg-icon-Pattern-2\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"divider-border-wrap divider-border-right\">\n\t\t\t\t\t\t\t\t<span class=\"divider-border\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-a8a8379 e-grid e-con-full e-con e-child\" data-id=\"a8a8379\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a162fcb elementor-view-stacked elementor-shape-square learn-connect-cards elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"a162fcb\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon diamond-and-gemstone-icon-012-jewellery\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0627\u0644\u062e\u0628\u0631\u0629\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u064a\u0636\u0645 \u0641\u0631\u064a\u0642\u0646\u0627 \u062e\u0628\u0631\u0627\u0621 \u0645\u0639\u062a\u0645\u062f\u064a\u0646 \u062d\u0627\u0635\u0644\u064a\u0646 \u0639\u0644\u0649 \u0634\u0647\u0627\u062f\u0627\u062a \u0639\u0627\u0644\u0645\u064a\u0629 \u0645\u0646 **GIA** \u0627\u0644\u0623\u0645\u0631\u064a\u0643\u064a\u0629\u060c \u0648\u064a\u062a\u0645\u062a\u0639\u0648\u0646 \u0628\u062e\u0628\u0631\u0629 \u0648\u0627\u0633\u0639\u0629 \u0641\u064a \u0639\u0644\u0648\u0645 \u0627\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629 \u0648\u0627\u0644\u0623\u0644\u0645\u0627\u0633\u060c \u0645\u0645\u0627 \u064a\u0636\u0645\u0646 \u062a\u0642\u062f\u064a\u0645 \u0623\u0641\u0636\u0644 \u0627\u0644\u062e\u062f\u0645\u0627\u062a.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a07d095 elementor-view-stacked elementor-shape-square learn-connect-cards elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"a07d095\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon diamond-and-gemstone-icon-011-diamond-5\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0627\u0644\u062c\u0648\u062f\u0629\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u0646\u0644\u062a\u0632\u0645 \u0628\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0623\u062d\u062f\u062b \u0627\u0644\u0623\u062c\u0647\u0632\u0629 \u0648\u0627\u0644\u062a\u0642\u0646\u064a\u0627\u062a \u0644\u0636\u0645\u0627\u0646 \u062f\u0642\u0629 \u0648\u0645\u0648\u062b\u0648\u0642\u064a\u0629 \u062a\u0642\u0627\u0631\u064a\u0631\u0646\u0627.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-cc62fe3 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"cc62fe3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-10ff642 e-con-full bg-moving-animation-smx e-flex e-con e-child\" data-id=\"10ff642\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-9092001 e-con-full e-flex e-con e-child\" data-id=\"9092001\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b35b83 testimonials elementor-widget elementor-widget-eael-testimonial-slider\" data-id=\"7b35b83\" data-element_type=\"widget\" data-settings=\"{&quot;items&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;items_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;items_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;slide_items&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;slide_items_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;slide_items_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]}}\" data-widget_type=\"eael-testimonial-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"swiper-container-wrap swiper-container-wrap-dots-outside eael-testimonial-slider content-top-icon-title-inline\" id=\"eael-testimonial-7b35b83\">\n\t\t\t            <div class=\"swiper swiper-8 eael-testimonial-slider-main swiper-container-7b35b83\" data-pagination=\".swiper-pagination-7b35b83\" data-arrow-next=\".swiper-button-next-7b35b83\" data-arrow-prev=\".swiper-button-prev-7b35b83\" data-items=\"1\" data-items-tablet=\"1\" data-items-mobile=\"1\" data-slide-items=\"1\" data-slide-items-tablet=\"1\" data-slide-items-mobile=\"1\" data-margin=\"10\" data-effect=\"slide\" data-speed=\"1000\" data-loop=\"1\" data-dots=\"1\" data-autoplay_speed=\"2000\">\n\n                <div class=\"swiper-wrapper\">\n\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t                        <div class=\"eael-testimonial-item clearfix swiper-slide  eael-testimonial-align-right\">\n                            <div class=\"eael-testimonial-item-inner clearfix\">\n                                <div class=\"eael-testimonial-content \" style=\" height: px;\">\n\t\t\t\t\t\t\t\t\t<span class=\"eael-testimonial-quote\"><\/span><div class=\"eael-testimonial-text \"><p>\u0644\u0648\u0631\u064a\u0645 \u0625\u064a\u0628\u0633\u0648\u0645 \u062f\u0648\u0644\u0627\u0631 \u0633\u064a\u062a \u0623\u0645\u064a\u062a\u060c \u0643\u0648\u0646\u0633\u064a\u0643\u062a\u064a\u062a\u0648\u0631 \u0623\u062f\u064a\u0628\u064a\u0633\u064a\u0646\u063a \u0625\u064a\u0644\u064a\u062a. \u062f\u0648\u0646\u0643 \u0623 \u0641\u064a\u0648\u063a\u0627\u062a \u0628\u0648\u0631\u0648\u0633. \u062f\u0648\u064a\u0633 \u062a\u0648\u0631\u0628\u064a\u0633 \u0646\u0648\u0646\u0643 \u0623\u0644\u064a\u0643\u0648\u0627\u0645 \u0625\u064a\u062f \u0646\u0648\u0646\u0643 \u0623\u0643\u0643\u0648\u0646\u0641\u0627\u0644\u064a\u0633 \u062f\u064a\u0643\u062a\u0648\u0645 \u0646\u064a\u0633\u064a. \u0643\u0648\u0631\u0627\u0628 \u0625\u064a\u062a\u0648\u0631 \u0641\u064a\u0647\u0643\u0648\u0644\u0627 \u062a\u064a\u0646\u0643\u064a\u0646\u062f\u0646\u062a \u0633\u0627\u0628\u064a\u064a\u0646 \u0641\u064a\u0644\u0643\u0627\u0643. \u062f\u0648\u0646\u0643 \u062f\u064a\u0627\u0645 \u0623\u0648\u062c\u0648 \u0643\u0648\u0646\u0633\u0643\u0627\u062a \u0633\u064a\u062a \u0623\u0645\u064a\u062a \u0645\u064a\u062a\u0648\u0633 \u0623\u0643\u0628\u064a\u0628\u0646\u062f\u0648\u0645 \u0645\u0627\u062a\u064a\u0633 \u0645\u0627\u0633\u0627. \u062f\u0648\u064a\u0633 \u0645\u0648\u0644\u064a\u0633 \u0644\u064a\u063a\u0648\u0644\u0627 \u0628\u0631\u064a\u062a\u064a\u0648\u0645 \u0643\u0648\u0646\u0633\u0643\u0627\u062a \u0623\u0644\u064a\u0643\u064a\u062a \u0646\u064a\u0628\u0648\u0631 \u0628\u0648\u0631\u0648\u0648\u0633 \u0641\u064a\u0631\u0645\u0646\u062a\u0648 \u0643\u0648\u0646\u0633\u0643\u0627\u062a\u0645\u064a.<\/p><\/div>                                    <div class=\"testimonial-inline-style\">\n\t\t\t\t\t\t\t\t\t\t        <div class=\"eael-testimonial-image\">\n\t\t\t            <figure>\n                <img decoding=\"async\" src=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/2024\/08\/fashion-portrait-of-beautiful-woman-with-tiara-on-head-150x150-1.jpg\" alt=\"\">\n            <\/figure>\n        <\/div>\n\t\t        <p class=\"eael-testimonial-user\" >\u0623\u0648\u0644\u0641\u0627 \u0648\u064a\u0644\u0643\u0646\u0633\u0648\u0646<\/p>\n        <p class=\"eael-testimonial-user-company\">\u0639\u0645\u064a\u0644<\/p>\n\t\t                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t                        <div class=\"eael-testimonial-item clearfix swiper-slide  eael-testimonial-align-right\">\n                            <div class=\"eael-testimonial-item-inner clearfix\">\n                                <div class=\"eael-testimonial-content \" style=\" height: px;\">\n\t\t\t\t\t\t\t\t\t<span class=\"eael-testimonial-quote\"><\/span><div class=\"eael-testimonial-text \"><p>\u0644\u0648\u0631\u064a\u0645 \u0625\u064a\u0628\u0633\u0648\u0645 \u062f\u0648\u0644\u0627\u0631 \u0633\u064a\u062a \u0623\u0645\u064a\u062a\u060c \u0643\u0648\u0646\u0633\u064a\u0643\u062a\u064a\u062a\u0648\u0631 \u0623\u062f\u064a\u0628\u064a\u0633\u064a\u0646\u063a \u0625\u064a\u0644\u064a\u062a. \u062f\u0648\u0646\u0643 \u0623 \u0641\u064a\u0648\u063a\u0627\u062a \u0628\u0648\u0631\u0648\u0633. \u062f\u0648\u064a\u0633 \u062a\u0648\u0631\u0628\u064a\u0633 \u0646\u0648\u0646\u0643 \u0623\u0644\u064a\u0643\u0648\u0627\u0645 \u0625\u064a\u062f \u0646\u0648\u0646\u0643 \u0623\u0643\u0643\u0648\u0646\u0641\u0627\u0644\u064a\u0633 \u062f\u064a\u0643\u062a\u0648\u0645 \u0646\u064a\u0633\u064a. \u0643\u0648\u0631\u0627\u0628 \u0625\u064a\u062a\u0648\u0631 \u0641\u064a\u0647\u0643\u0648\u0644\u0627 \u062a\u064a\u0646\u0643\u064a\u0646\u062f\u0646\u062a \u0633\u0627\u0628\u064a\u064a\u0646 \u0641\u064a\u0644\u0643\u0627\u0643. \u062f\u0648\u0646\u0643 \u062f\u064a\u0627\u0645 \u0623\u0648\u062c\u0648 \u0643\u0648\u0646\u0633\u0643\u0627\u062a \u0633\u064a\u062a \u0623\u0645\u064a\u062a \u0645\u064a\u062a\u0648\u0633 \u0623\u0643\u0628\u064a\u0628\u0646\u062f\u0648\u0645 \u0645\u0627\u062a\u064a\u0633 \u0645\u0627\u0633\u0627. \u062f\u0648\u064a\u0633 \u0645\u0648\u0644\u064a\u0633 \u0644\u064a\u063a\u0648\u0644\u0627 \u0628\u0631\u064a\u062a\u064a\u0648\u0645 \u0643\u0648\u0646\u0633\u0643\u0627\u062a \u0623\u0644\u064a\u0643\u064a\u062a \u0646\u064a\u0628\u0648\u0631 \u0628\u0648\u0631\u0648\u0648\u0633 \u0641\u064a\u0631\u0645\u0646\u062a\u0648 \u0643\u0648\u0646\u0633\u0643\u0627\u062a\u0645\u064a.<\/p><\/div>                                    <div class=\"testimonial-inline-style\">\n\t\t\t\t\t\t\t\t\t\t        <div class=\"eael-testimonial-image\">\n\t\t\t            <figure>\n                <img decoding=\"async\" src=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/2024\/08\/fashion-portrait-of-beautiful-woman-with-tiara-on-head-150x150-1.jpg\" alt=\"\">\n            <\/figure>\n        <\/div>\n\t\t        <p class=\"eael-testimonial-user\" >\u0623\u0648\u0644\u0641\u0627 \u0648\u064a\u0644\u0643\u0646\u0633\u0648\u0646<\/p>\n        <p class=\"eael-testimonial-user-company\">\u0639\u0645\u064a\u0644<\/p>\n\t\t                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t                <\/div>\n\t\t\t\t            <!-- Add Pagination -->\n            <div class=\"swiper-pagination swiper-pagination-7b35b83\"><\/div>\n\t\t            <\/div>\n\t\t\t        <\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4841d84 elementor-widget__width-auto elementor-widget-mobile__width-initial elementor-absolute elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4841d84\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"flaticonseicon- flaticonse-icon-right-quote\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-ff50de0 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"ff50de0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aab450d elementor-absolute elementor-widget elementor-widget-image\" data-id=\"aab450d\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/elementor\/thumbs\/Asset-1-scaled-1-qt1q44ag22lk0qv9getnhzumncquhfu4et0hleseps.jpg\" title=\"Asset-1-scaled.jpg\" alt=\"Asset-1-scaled.jpg\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-0c28132 e-con-full e-flex e-con e-parent\" data-id=\"0c28132\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-621288a elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"621288a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u062a\u0627\u0628\u0639\u0646\u0627<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c763c2 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"0c763c2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">@idg.instagram<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d86d05f elementor-widget elementor-widget-image-carousel\" data-id=\"d86d05f\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/elementor\/thumbs\/diamond-ring-e1615346982949-qt1i8eo1voh4x1oaq6vmznwr2hatu5i4d6edhx4neg.jpg\" alt=\"diamond-ring-e1615346982949\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/elementor\/thumbs\/goldplated-necklace-e1615346995392-qt1i8gjq9cjpk9lkf7ow4nfo991k9jpl1fpcgh1v20.jpg\" alt=\"goldplated-necklace-e1615346995392\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/elementor\/thumbs\/necklace-with-stones-e1615346988781-qt1i8ifen0ma7hiu48i59mylg0saoxx1pp0bf0z2pk.jpg\" alt=\"necklace-with-stones-e1615346988781\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/idg-lab.com.sa\/wp-content\/uploads\/elementor\/thumbs\/silver-bracelet-and-necklace-e1615346976355-qt1i8jd8tunkj3hgyqwru4q21ennwn0s1tnswaxojc.jpg\" alt=\"silver-bracelet-and-necklace-e1615346976355\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Variety Royal&nbsp;Edition High&nbsp;Diamond Just For A Queens \u062f\u0639\u0648\u0646\u0627 \u0646\u062e\u062a\u0628\u0631&nbsp;\u062c\u0648\u0627\u0647\u0631\u0643 \u0646\u062e\u062a\u0628\u0631&nbsp;\u062c\u0648\u0627\u0647\u0631\u0643 \u0644\u0644\u062a\u0623\u0643\u062f \u0645\u0646 \u0635\u062d\u062a\u0647\u0627! IDG \u0647\u0648 \u0645\u062e\u062a\u0628\u0631 \u0631\u0627\u0626\u062f \u0645\u062a\u062e\u0635\u0635 \u0641\u064a \u0641\u062d\u0635 \u0648\u062a\u0642\u064a\u064a\u0645 \u0627\u0644\u0623\u062d\u062c\u0627\u0631 \u0627\u0644\u0643\u0631\u064a\u0645\u0629 \u0648\u0627\u0644\u0623\u0644\u0645\u0627\u0633. \u0627\u062a\u0635\u0644 \u0628\u0646\u0627 \u062a\u0648\u064a\u062a\u0631 \u0627\u0646\u0633\u062a\u062c\u0631\u0627\u0645 \u0644\u064a\u0646\u0643\u062f\u0625\u0646 \u062a\u064a\u0643 \u062a\u0648\u0643 \u0639\u0646\u0648\u0627\u0646 \u0645\u0631\u0643\u0632 \u0627\u0644\u0623\u0646\u062f\u0644\u0633 \u0627\u0644\u062a\u062c\u0627\u0631\u064a \u0628\u0648\u0627\u0628\u0629 \u0666 \u0627\u0644\u062f\u0648\u0631\u00a0\u0627\u0644\u0627\u0648\u0644 \u062a\u0648\u0627\u0635\u0644 \u0645\u0639\u0646\u0627 E : info@idg-lab.com.sa \u0646\u0628\u0630\u0629 \u0639\u0646 IDG \u064a\u064f\u0639\u062f \u0645\u062e\u062a\u0628\u0631 IDG \u0645\u062e\u062a\u0628\u0631\u064b\u0627 \u0633\u0639\u0648\u062f\u064a\u064b\u0627 \u0645\u062a\u062e\u0635\u0635\u064b\u0627 \u0641\u064a \u0641\u062d\u0635 \u0648\u062a\u0642\u064a\u064a\u0645 [&#8230;]\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header-light.php","meta":{"footnotes":""},"class_list":["post-25","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/idg-lab.com.sa\/ar\/wp-json\/wp\/v2\/pages\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/idg-lab.com.sa\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/idg-lab.com.sa\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/idg-lab.com.sa\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/idg-lab.com.sa\/ar\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":172,"href":"https:\/\/idg-lab.com.sa\/ar\/wp-json\/wp\/v2\/pages\/25\/revisions"}],"predecessor-version":[{"id":2948,"href":"https:\/\/idg-lab.com.sa\/ar\/wp-json\/wp\/v2\/pages\/25\/revisions\/2948"}],"wp:attachment":[{"href":"https:\/\/idg-lab.com.sa\/ar\/wp-json\/wp\/v2\/media?parent=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}